{"id":11473,"date":"2018-06-06T14:00:35","date_gmt":"2018-06-06T20:00:35","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=11473"},"modified":"2018-06-06T14:03:15","modified_gmt":"2018-06-06T20:03:15","slug":"mi-profesion-me-permite-proponer-acciones-en-favor-del-desarrollo-urbano-del-municipiotono-costa","status":"publish","type":"post","link":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/mi-profesion-me-permite-proponer-acciones-en-favor-del-desarrollo-urbano-del-municipiotono-costa\/","title":{"rendered":"PROPONE TO\u00d1O COSTA REORDENAMIENTO URBANO PARA TAMAZUNCHALE"},"content":{"rendered":"<p>To\u00f1o Costa propone un reordenamiento urbano en Tamazunchale para desahogar el estancamiento que vivimos en la zona centro de nuestro municipio.<\/p>\n<p>El candidato mencion\u00f3 que no ha habido un proyecto de Desarrollo Urbano, el \u00fanico que se realiz\u00f3 fue en la administraci\u00f3n 1997 \u2013 2000, cuando ostent\u00f3 el cargo como Director de Obras P\u00fablicas, pero ya no tuvo seguimiento y se qued\u00f3 perdido.<\/p>\n<p>Comenta que el crecimiento an\u00e1rquico de la ciudad, est\u00e1\u00a0 provocando la asfixia del pueblo, que hay una v\u00eda p\u00fablica invadida y que los mismos comerciantes aceptan que esas condiciones no les favorecen ya que los lugares son inapropiados.<\/p>\n<p>Para poder encontrar una soluci\u00f3n se debe primero recurrir al di\u00e1logo analizando bien el problema y luego buscar una soluci\u00f3n congruente, dijo: \u201cYo hago diagn\u00f3sticos, mi profesi\u00f3n de arquitecto me permite tener esa visi\u00f3n para proponer acciones de soluci\u00f3n\u201d, coment\u00f3.<\/p>\n<p>Dijo que en ese dialogar se deben reunir todos los involucrados, gobierno, comerciantes, transportistas y todo aquel que tenga que ver para rescatar la zona centro del Tamazunchale de antes y buscar opciones, as\u00ed como la b\u00fasqueda de un espacio para reubicar pero hacerlo bien, no solo por ocurrencia<\/p>\n<p>\u201cDebemos analizar cuantos comercios hay, que superficie ocupan y saber que superficie necesitamos para reubicarlos;\u00a0 pero desafortunadamente no hay mucha voluntad para arreglar ese problema, sin embargo lo principal aqu\u00ed es agotar el dialogo, no voy a llegar a desalojar las calles como muchos lo han mencionado, eso es il\u00f3gico\u201d, mencion\u00f3 el candidato de la coalici\u00f3n Por M\u00e9xico al Frente.<\/p>\n<p>Dijo que esta actividad se ha dejado crecer cada vez m\u00e1s, no se ha podido ni siquiera contener, pero que juntos se encontrar\u00e1n propuestas congruentes con soportes objetivos sobre los intereses del pueblo y aplicar la ley que se ha perdido desde hace muchos a\u00f1os en este tema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>To\u00f1o Costa propone un reordenamiento urbano en Tamazunchale para desahogar el estancamiento que vivimos en la zona centro de nuestro<\/p>\n","protected":false},"author":2,"featured_media":11475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11473"}],"collection":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=11473"}],"version-history":[{"count":4,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11473\/revisions"}],"predecessor-version":[{"id":11478,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11473\/revisions\/11478"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/11475"}],"wp:attachment":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=11473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=11473"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=11473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}