{"id":11480,"date":"2018-06-06T14:52:39","date_gmt":"2018-06-06T20:52:39","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=11480"},"modified":"2018-06-06T14:52:39","modified_gmt":"2018-06-06T20:52:39","slug":"congreso-llevo-a-cabo-sesion-parlamentaria-de-los-ninos-y-las-ninas-edicion-2018","status":"publish","type":"post","link":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/congreso-llevo-a-cabo-sesion-parlamentaria-de-los-ninos-y-las-ninas-edicion-2018\/","title":{"rendered":"CONGRESO LLEVO A CABO SESI\u00d3N PARLAMENTARIA DE LOS NI\u00d1OS Y LAS NI\u00d1AS, EDICI\u00d3N 2018"},"content":{"rendered":"<p>Durante la sesi\u00f3n especial del Parlamento de los Ni\u00f1os y las Ni\u00f1as, edici\u00f3n 2018, los menores potosinos demandaron establecer programas de ayuda social para los ni\u00f1os y las ni\u00f1as que no cuenten con recursos econ\u00f3micos suficientes y a la vez concientizar a los padres de familia al no trabajo prematuro de los mismos, ya que es urgente atender sectores de pobreza y marginaci\u00f3n donde la mayor\u00eda de la poblaci\u00f3n infantil tiene que trabajar para apoyar al sostenimiento familiar y solventar algunas de sus necesidades, las m\u00e1s importantes como lo son la alimentaci\u00f3n y la educaci\u00f3n.<\/p>\n<p>Tambi\u00e9n pidieron mayores acciones para combatir la pobreza, inseguridad, desempleo, maltrato infantil y que se construyan m\u00e1s escuelas de calidad porque, dijeron, en la medida en que los menores est\u00e9n en clases, se evita que realicen acciones il\u00edcitas.<\/p>\n<p>Al aprobar y emitir la declaratoria del Parlamento de los Ni\u00f1os y las Ni\u00f1as, edici\u00f3n 2018, demandaron a las autoridades realizar acciones educativas y preventivas a fin de evitar que se cometan il\u00edcitos en contra de los ni\u00f1os y las ni\u00f1as.<\/p>\n<p>A los maestros que dise\u00f1en y apliquen las medidas conducentes para crear y propiciar relaciones de igualdad entre los educandos, hombres mujeres al interior de las aulas, a fin de identificar y prevenir situaciones violentas por cuestiones de g\u00e9nero y, en consecuencia, evitar la discriminaci\u00f3n. Adem\u00e1s, que propicien el rechazo a los vicios y adicciones, fomentando el conocimiento de sus causas, riesgos y consecuencias.<\/p>\n<p>Expusieron que la educaci\u00f3n es un derecho humano y un medio vital para promover la paz y el respeto por los derechos humanos y las libertades\u00a0 fundamentales para construir un mundo m\u00e1s pac\u00edfico que\u00a0 busque ser igualitario para todos.<\/p>\n<p>Pidieron fomentar entre los ni\u00f1os el uso adecuado y responsable de las tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n, el conocimiento y la conciencia respecto de las mejores pr\u00e1cticas para hacer uso apropiado de Internet y de las redes sociales; entre otras demandas.<\/p>\n<p>Al principio de la sesi\u00f3n especial del Parlamento de los Ni\u00f1os y las Ni\u00f1as, edici\u00f3n 2018, se eligi\u00f3 a la Directiva, la cual qued\u00f3 integrada por Rodolfo Dur\u00e1n Leal como presidente; Rodrigo del \u00c1ngel Mart\u00ednez Arellano, Primer Vicepresidente; Jes\u00fas Alejandro Zamora Huerta, Segundo Vicepresidente; Miroslava Rodr\u00edguez Fern\u00e1ndez, Primera Secretaria;\u00a0 Juli\u00e1n Rodr\u00edguez Quevedo, Segundo Secretario;\u00a0 Manuel Gayt\u00e1n Morales, Primer Prosecretario; y Vielka Fernanda Gonz\u00e1lez Blanco, Segunda Prosecretario.<\/p>\n<p>El Parlamento de los Ni\u00f1os y las Ni\u00f1as, edici\u00f3n 2018, estuvo integrado por Yazm\u00edn Egu\u00eda Hern\u00e1ndez, de Matehuala y como representante del distrito I; Leonardo Gael Cura Gonz\u00e1lez, de Venado y representante del distrito II; Francisco \u00c1ngel Mart\u00ednez Mart\u00ednez, de Tierra Nueva y representante del distrito III; Paulina Janeth Alaniz Garc\u00eda, \u00a0de Salinas de Hidalgo y representante del distrito IV; Cassandra Cisnero Mateos, de la capital potosina y representante del distrito V; Juan Jos\u00e9 Vel\u00e1zquez Coronado, de la capital potosina y representante del distrito VI; Vielka Fernanda Gonz\u00e1lez Blanco, de la capital potosina y representante del distrito VII.<\/p>\n<p>Alejandro Torres L\u00f3pez, de la capital potosina y representante del distrito VIII; Alan Said L\u00f3pez L\u00f3pez, de Soledad de Graciano S\u00e1nchez y representante del distrito IX; Cristian Daniel Cruz Torres, de Rioverde y representante del distrito X; Juan Jes\u00fas M\u00e9ndez Garibaldi, de Ciudad del Ma\u00edz y representante del distrito XI; Vicente L\u00f3pez Gonz\u00e1lez, de Ciudad Valles y representante del distrito XII; Rodolfo Dur\u00e1n Leal, de Tamu\u00edn y represente del distrito XIII; Marissa Cort\u00e9s Salinas, de Axtla de Terrazas y representante del distrito XIV y Rodrigo del \u00c1ngel Mart\u00ednez Arellanos, de Tamazunchale y representante del distrito XV.<\/p>\n<p>Adem\u00e1s como parlamentarios de representaci\u00f3n proporcional \u00c1ngel Arturo Rivera Hern\u00e1ndez, de la capital potosina; Paloma Sharibel Gamez Delgado, de la capital potosina; Alicia Estefania Hinojosa Lucio, de la capital potosina; Juli\u00e1n Rodr\u00edguez Quevedo, de Rioverde; Oscar Alberto Gauna Moreno, de la capital potosina; Manuel Gait\u00e1n Morales, de la capital potosina; Miroslava Rodr\u00edguez Fern\u00e1ndez, de la capital potosina; Jesus Alejandro Zamora Huerta, de la capital potosina; Grecia de Angelis Loredo Guerrera, de la capital potosina; David Alejandro Trist\u00e1n Contreras, de la capital potosina; Berenice Quitzia Flores Leija y Andrea Jazm\u00edn Campos G\u00f3ngora, ambas de Soledad de Graciano S\u00e1nchez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la sesi\u00f3n especial del Parlamento de los Ni\u00f1os y las Ni\u00f1as, edici\u00f3n 2018, los menores potosinos demandaron establecer programas<\/p>\n","protected":false},"author":2,"featured_media":11481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11480"}],"collection":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=11480"}],"version-history":[{"count":1,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11480\/revisions"}],"predecessor-version":[{"id":11482,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11480\/revisions\/11482"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/11481"}],"wp:attachment":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=11480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=11480"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=11480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}