{"id":11502,"date":"2018-06-06T12:12:17","date_gmt":"2018-06-06T18:12:17","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=11502"},"modified":"2018-06-07T12:12:30","modified_gmt":"2018-06-07T18:12:30","slug":"gobernador-supervisa-obras-de-infraestructura-educativa-en-slp","status":"publish","type":"post","link":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/gobernador-supervisa-obras-de-infraestructura-educativa-en-slp\/","title":{"rendered":"GOBERNADOR SUPERVISA OBRAS DE INFRAESTRUCTURA EDUCATIVA EN SLP"},"content":{"rendered":"<ul>\n<li><strong>En SDGS se encuentran los primeros planteles escolares con un sistema fotovoltaico para generaci\u00f3n de energ\u00edas limpias<\/strong><\/li>\n<\/ul>\n<p>Autoridades educativas estatales, encabezadas por el Gobernador del Estado, supervisaron obras de infraestructura en tres centros escolares de la zona metropolitana de San Luis Potos\u00ed,\u00a0 donde destaca la visita a los planteles \u201cHero\u00ednas Mexicanas\u201d y el jard\u00edn de ni\u00f1os \u201cMar\u00eda Teresa \u00c1lvarez\u201d en el fraccionamiento valle de la Cruz, que cuentan con sistema fotovoltaico, los primeros de la entidad en instituciones p\u00fablicas.<\/p>\n<p>Aqu\u00ed el titular del Ejecutivo, dio a conocer que el desarrollo de esta infraestructura beneficia a m\u00e1s de 390 alumnos de ambas comunidades educativas, con ahorros de energ\u00eda equivalente a reducir casi 17 toneladas de CO2, que ser\u00edan emitidos hacia nuestra atm\u00f3sfera, aunado a que representan ahorros de m\u00e1s del 90 por ciento para los planteles educativos.<\/p>\n<p>La directora del jard\u00edn de ni\u00f1os \u201cMar\u00eda Teresa \u00c1lvarez\u201d, la profesora Abril Silva God\u00ednez, detall\u00f3 que con estos importantes ahorros en consumo se beneficia directamente toda la comunidad educativa, ya que se pueden destinar los recursos otro tipo de proyectos que van en beneficio directo de los centros educativos.<\/p>\n<p>Para el director de la escuela primaria \u201cHero\u00ednas Mexicanas\u201d, contar con tecnolog\u00eda de vanguardia a nivel nacional constituye un importante reto y avance, ya que trae consigo ahorros en el consumo de energ\u00eda, aunado a que es fundamental contar con el respaldo del Gobernador del Estado para detonar proyectos a nivel nacional que benefician a la ni\u00f1ez potosina.<\/p>\n<p>El titular de la Secretar\u00eda de Educaci\u00f3n del Gobierno del Estado, explic\u00f3 que \u201ceste proyecto es el primero de este tipo en San Luis Potos\u00ed para escuelas de educaci\u00f3n b\u00e1sica publica, lo que permite abrir las puertas a una nueva etapa en el consumo de energ\u00edas limpias que van en beneficio de nuestro pa\u00eds\u201d.<\/p>\n<p>Como parte de la gira de trabajo por la ma\u00f1ana el Gobernador supervis\u00f3 las obras de mejoramiento de la infraestructura f\u00edsica educativa del jard\u00edn de ni\u00f1os \u201cLeonor Ch\u00e1vez Zubeld\u00eda\u201d, ubicada en el fraccionamiento Haciendas de Juan Pablo, en el norte de la ciudad, que consisti\u00f3 en la construcci\u00f3n de 3 aulas did\u00e1cticas, direcci\u00f3n y servicios sanitarios, as\u00ed como obras perimetrales y exteriores el\u00e9ctricas.<\/p>\n<p>En su intervenci\u00f3n, el mandatario estatal dijo que \u201cEn las casas se les ense\u00f1a a las ni\u00f1os y ni\u00f1as disciplina, valores y respeto y las escuelas complementan la educaci\u00f3n ense\u00f1\u00e1ndoles herramientas para salir adelante\u201d, puntualiz\u00f3.<\/p>\n<p>Posteriormente, en la colonia Ciudad 2000, en el oriente de la ciudad, el mandatario estatal realiz\u00f3 un recorrido de supervisi\u00f3n de\u00a0 la construcci\u00f3n de 2 aulas did\u00e1cticas y un aula de m\u00fasica con su respectivo equipamiento, que beneficia al jard\u00edn de ni\u00f1os del turno matutino \u201cLuz Mar\u00eda Serradel\u201d y turno vespertino \u201cWilliam Shakespeare\u201d.<\/p>\n<p>Ah\u00ed mismo, el mandatario potosino entreg\u00f3 40 reconocimientos a la Banda de Guerra del jard\u00edn de ni\u00f1os \u201cLuz Mar\u00eda Serradel\u201d, que particip\u00f3 en el Encuentro del Circuito Metropolitano de Bandas de Guerras y Escoltas de Bandera, que se realiz\u00f3 en la ciudad de Quer\u00e9taro. Adem\u00e1s, presenci\u00f3 un festival preparado por las ni\u00f1as y ni\u00f1os de danza y bailables regionales, as\u00ed como la interpretaci\u00f3n de m\u00fasica del coro del centro escolar.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En SDGS se encuentran los primeros planteles escolares con un sistema fotovoltaico para generaci\u00f3n de energ\u00edas limpias Autoridades educativas estatales,<\/p>\n","protected":false},"author":2,"featured_media":11503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11502"}],"collection":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=11502"}],"version-history":[{"count":1,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11502\/revisions"}],"predecessor-version":[{"id":11504,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11502\/revisions\/11504"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/11503"}],"wp:attachment":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=11502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=11502"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=11502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}