{"id":54398,"date":"2024-01-08T13:03:00","date_gmt":"2024-01-08T19:03:00","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=54398"},"modified":"2024-01-11T13:10:48","modified_gmt":"2024-01-11T19:10:48","slug":"gobierno-estatal-brindo-apoyo-y-atendio-reportes-por-rafagas-de-viento","status":"publish","type":"post","link":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/gobierno-estatal-brindo-apoyo-y-atendio-reportes-por-rafagas-de-viento\/","title":{"rendered":"GOBIERNO ESTATAL BRIND\u00d3 APOYO Y ATENDI\u00d3 REPORTES POR R\u00c1FAGAS DE VIENTO"},"content":{"rendered":"\n<p>La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC), brind\u00f3 apoyo a los m\u00e1s de 33 reportes ciudadanos generados derivado de las condiciones clim\u00e1ticas del frente fr\u00edo 25 y la cuarta tormenta invernal de la temporada, que provocaron bajas temperaturas y r\u00e1fagas de viento de entre 50 y 80 kil\u00f3metros por hora principalmente en la zona Centro y Altiplano, atendidos en coordinaci\u00f3n con los ayuntamientos de la capital y Soledad y con la Secretar\u00eda de Desarrollo Urbano, Vivienda y Obras P\u00fablicas (Seduvop).<\/p>\n\n\n\n<p>El director de la Mauricio Ordaz Flores, detall\u00f3 que al momento se han recibido 33 reportes, 23 de \u00e1rboles ca\u00eddos, 6 de ellos sobre veh\u00edculos, siete de espectaculares o que se han ca\u00eddo o bien con alg\u00fan da\u00f1o en las lonas, dos postes de luz ca\u00eddos por los fuertes vientos y un \u00e1rbol ca\u00eddo en una vivienda en la calle de la Colonia Jard\u00edn.<\/p>\n\n\n\n<p>Precis\u00f3 que de acuerdo a la instrucci\u00f3n del Gobernador de San Luis Potos\u00ed, Ricardo Gallardo Cardona, se trabaja para retirar \u00e1rboles y ramas en el Boulevard del R\u00edo Santiago y acordonar zonas de riesgo para los automovilistas, adem\u00e1s que desde temprana hora se solicit\u00f3 cerrar los parques Tangamanga I y II y se mantiene comunicaci\u00f3n con la Secretar\u00eda de Educaci\u00f3n para pedir que se eviten realizar actividades al aire libre en los planteles educativos.<\/p>\n\n\n\n<p>Finalmente dijo que estas condiciones pueden prevalecer en lo que resta del d\u00eda por lo que pidi\u00f3 a la poblaci\u00f3n tomar en cuenta las siguientes recomendaciones: evitar realizar trabajos en altura, no tocar cables el\u00e9ctricos que se hayan desprendido, no refugiarse del viento bajo \u00e1rboles o estructuras y asegurar objetos de azoteas o ventanas que puedan desprenderse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC), brind\u00f3 apoyo a los m\u00e1s de 33 reportes ciudadanos generados derivado de las<\/p>\n","protected":false},"author":1,"featured_media":54399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/54398"}],"collection":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=54398"}],"version-history":[{"count":1,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/54398\/revisions"}],"predecessor-version":[{"id":54400,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/54398\/revisions\/54400"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/54399"}],"wp:attachment":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=54398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=54398"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=54398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}