{"id":56838,"date":"2024-09-26T09:37:00","date_gmt":"2024-09-26T15:37:00","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=56838"},"modified":"2024-09-27T09:39:42","modified_gmt":"2024-09-27T15:39:42","slug":"ricardo-gallardo-anuncia-mas-infraestructura-y-obras-para-soledad","status":"publish","type":"post","link":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/ricardo-gallardo-anuncia-mas-infraestructura-y-obras-para-soledad\/","title":{"rendered":"RICARDO GALLARDO ANUNCIA M\u00c1S INFRAESTRUCTURA Y OBRAS PARA SOLEDAD"},"content":{"rendered":"\n<p>En el marco del tercer informe del ayuntamiento de Soledad de Graciano S\u00e1nchez, el Gobernador Ricardo Gallardo Cardona, anunci\u00f3 mejoras en movilidad, infraestructura h\u00eddrica y cultura, para llevar m\u00e1s apoyo a las y los soledenses y mejorar su calidad de vida, adem\u00e1s de fortalecer la proyecci\u00f3n tur\u00edstica a nivel nacional e internacional.<\/p>\n\n\n\n<p>Desde la cabecera municipal, el Mandatario Estatal anunci\u00f3 que a partir de febrero del 2025, para seguir modernizando las v\u00edas de comunicaci\u00f3n, el sistema MetroRed en Soledad se ampliar\u00e1 con una nueva l\u00ednea que conectar\u00e1 a C\u00e1ndido Navarro o Palma de la Cruz, con el centro del municipio y que llegar\u00e1 hasta la Alameda Juan Sarabia en la capital potosina de manera gratuita, lo que ayudar\u00e1 a las y los trabajadores que se trasladan para llevar sustento a sus hogares.<\/p>\n\n\n\n<p>Para combatir las omisiones de la herencia maldita en el abastecimiento de agua, Gallardo Cardona anunci\u00f3 que ser\u00e1n invertidos m\u00e1s de 200 millones de pesos para colectores pluviales en colonias como Cactus, San Luis I, Quintas de las Haciendas, entre otras, cerrar los canales de aguas negras y contribuir a que Soledad cuente con su propio organismo de agua potable y saneamiento, una vez que desaparezca Interapas.<\/p>\n\n\n\n<p>Durante el informe de la alcaldesa interina Araceli Mart\u00ednez P\u00e9rez, el Jefe del Ejecutivo Estatal destac\u00f3 que para modernizar y seguir consolidando la grandeza del municipio, modernizar\u00e1n la plaza p\u00fablica, convirti\u00e9ndola en una de las m\u00e1s grandes peatonales del Estado, adem\u00e1s de que el actual Palacio Municipal se convertir\u00e1 en el Museo del Tiempo, en donde expondr\u00e1n piezas hist\u00f3ricas y de arte, lo que ser\u00e1 posible a partir de que las y los funcionarios se trasladen a la nueva Unidad Administrativa, en avenida San Pedro y que a la brevedad ser\u00e1 entregada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del tercer informe del ayuntamiento de Soledad de Graciano S\u00e1nchez, el Gobernador Ricardo Gallardo Cardona, anunci\u00f3 mejoras<\/p>\n","protected":false},"author":1,"featured_media":56839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/56838"}],"collection":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=56838"}],"version-history":[{"count":1,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/56838\/revisions"}],"predecessor-version":[{"id":56840,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/56838\/revisions\/56840"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/56839"}],"wp:attachment":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=56838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=56838"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=56838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}