{"id":56911,"date":"2024-10-04T08:35:00","date_gmt":"2024-10-04T14:35:00","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=56911"},"modified":"2024-10-05T08:36:11","modified_gmt":"2024-10-05T14:36:11","slug":"federacion-y-el-estado-definen-a-nuevo-director-del-hospital-central","status":"publish","type":"post","link":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/federacion-y-el-estado-definen-a-nuevo-director-del-hospital-central\/","title":{"rendered":"FEDERACI\u00d3N Y EL ESTADO DEFINEN A NUEVO DIRECTOR DEL HOSPITAL CENTRAL"},"content":{"rendered":"\n<p>La titular de la Secretar\u00eda de Salud, Leticia Mariana G\u00f3mez Ordaz y el coordinador estatal del IMSS-Bienestar en el Estado, Daniel Acosta D\u00edaz de Le\u00f3n, formalizaron este 4 de octubre el nombramiento de Francisco Goldaracena Orozco, como nuevo director general del Hospital Central, a quien solicitaron trabajar para alcanzar el objetivo del Gobernador Ricardo Gallardo Cardona, de brindar una atenci\u00f3n m\u00e9dica oportuna y de calidad para las y los potosinos.&nbsp;&nbsp;<\/p>\n\n\n\n<p>El coordinador del IMSS-Bienestar agradeci\u00f3 a Javier Pinedo el trabajo realizado al frente del hospital y mencion\u00f3 que la instituci\u00f3n federal estar\u00e1 trabajando de manera conjunta con el Estado para mantener los est\u00e1ndares de atenci\u00f3n m\u00e9dica en el nosocomio.<\/p>\n\n\n\n<p>Goldaracena Orozco asumi\u00f3 la direcci\u00f3n del Hospital Central, consciente de los retos que enfrenta y de la necesidad de lograr una transici\u00f3n ordenada hacia el esquema IMSS-Bienestar, teniendo como prioridad la atenci\u00f3n m\u00e9dica para la poblaci\u00f3n que no cuenta con seguridad social.<\/p>\n\n\n\n<p>Goldaracena Orozco es egresado de la Universidad Aut\u00f3noma de San Luis Potos\u00ed, donde es catedr\u00e1tico desde 2011, cuenta con maestr\u00eda en Administraci\u00f3n de Instituciones de Salud y diplomado en Gesti\u00f3n de Hospitales por la Universidad Intercontinental y especialidad en pediatr\u00eda y subespecialidad en endocrinolog\u00eda pedi\u00e1trica. Es miembro del Consejo Mexicano de Endocrinolog\u00eda en Pediatr\u00eda y de la Mesa Directiva del Colegio de Endocrinolog\u00eda de San Luis Potos\u00ed. Ha prestado sus servicios en el Hospital del Ni\u00f1o y La Mujer como director general, adem\u00e1s del Hospital Central, donde es m\u00e9dico adscrito de Endocrinolog\u00eda Pedi\u00e1trica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La titular de la Secretar\u00eda de Salud, Leticia Mariana G\u00f3mez Ordaz y el coordinador estatal del IMSS-Bienestar en el Estado,<\/p>\n","protected":false},"author":1,"featured_media":56912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/56911"}],"collection":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=56911"}],"version-history":[{"count":1,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/56911\/revisions"}],"predecessor-version":[{"id":56913,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/56911\/revisions\/56913"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/56912"}],"wp:attachment":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=56911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=56911"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=56911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}