{"id":56948,"date":"2024-10-08T10:31:00","date_gmt":"2024-10-08T16:31:00","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=56948"},"modified":"2024-10-09T13:00:21","modified_gmt":"2024-10-09T19:00:21","slug":"lilia-malvido-nueva-directora-de-la-arena-potosi","status":"publish","type":"post","link":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/lilia-malvido-nueva-directora-de-la-arena-potosi\/","title":{"rendered":"LILIA MALVIDO NUEVA DIRECTORA DE LA ARENA POTOS\u00cd"},"content":{"rendered":"\n<p>Tras la inauguraci\u00f3n de la nueva Arena Potos\u00ed, el Gobernador del Estado Ricardo Gallardo Cardona, anunci\u00f3 a Lilia Malvido Flores como nueva directora del recinto, quien tendr\u00e1 la misi\u00f3n de generar una agenda de eventos y espect\u00e1culos internacionales que atraigan a miles de visitantes del pa\u00eds y del extranjero.<\/p>\n\n\n\n<p>Dijo que la Arena Potos\u00ed traer\u00e1 mucha fortaleza econ\u00f3mica al Estado, al congregar a miles de mexicanos a los espect\u00e1culos nacionales e internacionales que se realizar\u00e1n durante diferentes \u00e9pocas del a\u00f1o, lo que se traduce a brindar m\u00e1s apoyo en la reactivaci\u00f3n de los sectores econ\u00f3micos hotelero, restaurantero y de servicios.<\/p>\n\n\n\n<p>Gallardo Cardona puntualiz\u00f3 que Lilia Malvido Flores se desempe\u00f1\u00f3 como directora del Sistema de Financiamiento para el Desarrollo del Estado (Sifide) y durante el per\u00edodo que estuvo al frente de la dependencia impulso la creaci\u00f3n de nuevos programas de financiamiento, por lo que confi\u00f3 en que realizar\u00e1 un buen trabajo al frente de la Arena Potos\u00ed.<\/p>\n\n\n\n<p>Finalmente, el Gobernador destac\u00f3 que ahora San Luis Potos\u00ed se pone a la vanguardia de grandes ciudades de M\u00e9xico como Guadalajara, Monterrey y la capital del pa\u00eds, para recibir grandes espect\u00e1culos internacionales. Adelant\u00f3 que est\u00e1n en puerta los conciertos de los Tigres del Norte, Luis Miguel y el Congreso y Torneo Nacional Charro, adem\u00e1s el pr\u00f3ximo a\u00f1o se realizar\u00e1 el mundial de b\u00e9isbol infantil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la inauguraci\u00f3n de la nueva Arena Potos\u00ed, el Gobernador del Estado Ricardo Gallardo Cardona, anunci\u00f3 a Lilia Malvido Flores<\/p>\n","protected":false},"author":1,"featured_media":56953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/56948"}],"collection":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=56948"}],"version-history":[{"count":1,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/56948\/revisions"}],"predecessor-version":[{"id":56950,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/56948\/revisions\/56950"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/56953"}],"wp:attachment":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=56948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=56948"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=56948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}