{"id":60996,"date":"2025-09-13T10:25:00","date_gmt":"2025-09-13T16:25:00","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=60996"},"modified":"2025-09-15T10:28:29","modified_gmt":"2025-09-15T16:28:29","slug":"claudia-sheinbaum-y-ricardo-gallardo-van-juntos-por-mas-para-san-luis-potosi","status":"publish","type":"post","link":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/claudia-sheinbaum-y-ricardo-gallardo-van-juntos-por-mas-para-san-luis-potosi\/","title":{"rendered":"CLAUDIA SHEINBAUM Y RICARDO GALLARDO VAN JUNTOS POR M\u00c1S PARA SAN LUIS POTOS\u00cd"},"content":{"rendered":"\n<p>Durante el primer informe del Gobierno de M\u00e9xico desde San Luis Potos\u00ed, acompa\u00f1ada del Gobernador del Estado Ricardo Gallardo Cardona, la Presidenta de M\u00e9xico Claudia Sheinbaum Pardo, reafirm\u00f3 proyectos estrat\u00e9gicos para impulsar un crecimiento sin l\u00edmites entre los que destacan la construcci\u00f3n del tren de pasajeros de San Luis Potos\u00ed a Quer\u00e9taro y a Nuevo Laredo, las supercarreteras Ciudad Valles-Tampico y Tamazunchale-Huejutla y el aeropuerto de Tamu\u00edn.&nbsp;<\/p>\n\n\n\n<p>Al recibir a la Presidenta de la Rep\u00fablica en el centro de Negocios Potos\u00ed, el Mandatario potosino Ricardo Gallardo destac\u00f3 que, \u00abM\u00e9xico y San Luis Potos\u00ed viven su mejor momento, seguiremos caminando con usted en esta gran transformaci\u00f3n\u00bb, al agregar que el trabajo en el primer a\u00f1o se siente en cada rinc\u00f3n de San Luis Potos\u00ed.<\/p>\n\n\n\n<p>Durante su mensaje a las y los asistentes que se dieron cita este s\u00e1bado 13 de septiembre, Sheinbaum Pardo dio a conocer que actualmente se beneficia a m\u00e1s de 785 mil potosinas y potosinos con los programas del bienestar, quienes tambi\u00e9n reciben beneficios de los programas sociales estatales.<\/p>\n\n\n\n<p>Adicionalmente adelant\u00f3 proyectos en infraestructura como la construcci\u00f3n del tren de pasajeros, las supercarreteras Ciudad Valles-Tampico y Tamazunchale-Huejutla, la construcci\u00f3n de m\u00e1s de 40 mil viviendas por parte del Infonavit, nuevas escuelas preparatorias, el proyecto del hospital para Ciudad Valles y la construcci\u00f3n del aeropuerto de Tamu\u00edn, proyectos de infraestructura Federal que refuerzan el trabajo del Gobernador Ricardo Gallardo que en 4 a\u00f1os ha invertido m\u00e1s de 22 mil millones de pesos para importantes obras de infraestructura.<\/p>\n\n\n\n<p>Finalmente la Presidenta de M\u00e9xico dijo que se dispondr\u00e1n recursos federales para pagar los adeudos hist\u00f3ricos que se tienen con los maestros de telesecundarias resultado de la gesti\u00f3n del Gobernador Ricardo Gallardo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el primer informe del Gobierno de M\u00e9xico desde San Luis Potos\u00ed, acompa\u00f1ada del Gobernador del Estado Ricardo Gallardo Cardona,<\/p>\n","protected":false},"author":1,"featured_media":60997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/60996"}],"collection":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=60996"}],"version-history":[{"count":1,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/60996\/revisions"}],"predecessor-version":[{"id":60998,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/60996\/revisions\/60998"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/60997"}],"wp:attachment":[{"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=60996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=60996"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=60996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}