{"id":10946,"date":"2018-05-09T08:59:27","date_gmt":"2018-05-09T14:59:27","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=10946"},"modified":"2018-05-18T09:00:34","modified_gmt":"2018-05-18T15:00:34","slug":"la-osslp-interpreta-a-beethoven-y-brahms-en-el-teatro-de-la-paz","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/la-osslp-interpreta-a-beethoven-y-brahms-en-el-teatro-de-la-paz\/","title":{"rendered":"LA OSSLP INTERPRETA A BEETHOVEN Y BRAHMS EN EL TEATRO DE LA PAZ."},"content":{"rendered":"<ul>\n<li style=\"font-weight: 400;\"><b>Participa la pianista austriaca Hanna Bachmann, quien se presenta en San Luis Potos\u00ed por primera vez.<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Este viernes 11 de mayo a las 9 de la noche y domingo 13, a las 12:30 horas, la Orquesta Sinf\u00f3nica de San Luis Potos\u00ed interpretar\u00e1 dos obras emblem\u00e1ticas del Romanticismo: el Tercer Concierto para Piano, de Ludwig van Beethoven, y la Sinfon\u00eda no. 1, de Johannes Brahms, como parte de la Temporada de Conciertos Primavera-Verano 2018 que presenta en el Teatro de la Paz, en el que se recibe por primera vez como solista en nuestra ciudad a la pianista austriaca Hanna Bachmann.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bachmann es una\u00a0recitalista reconocida internacionalmente, que se presenta continuamente en Austria, Alemania, Hungr\u00eda, Italia, los Pa\u00edses Bajos, Eslovaquia, el Principado de Liechtenstein y Suiza, destacando sus participaciones en festivales especializados en m\u00fasica de Beethoven realizados en Bonn, Alemania, y destac\u00f3 su participaci\u00f3n en la Gala de Concierto para embajadores realizada en la Sala Musikverein, de Viena, el a\u00f1o pasado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hanna Bachmann interpretar\u00e1 con la OSSLP el Tercer Concierto para Piano en Do menor, Op.37, de Beethoven, este fin de semana, obra que representa un parteaguas en la m\u00fasica sinf\u00f3nica al mostrar la personalidad inconfundible del Genio de Bonn: sin salirse de las estructuras cl\u00e1sicas, introduce de forma innovadora mayor\u00a0importancia a las cualidades mel\u00f3dicas del instrumento solista y da mayor peso \u201csinf\u00f3nico\u201d a la orquesta; es decir, utiliza los diferentes timbres de \u00e9sta para plasmarla como un gran instrumento, logrando un punto de equilibrio entre la creaci\u00f3n hasta entonces tradicional de conciertos, con una nueva sensibilidad, generando el molde obligado de concierto cl\u00e1sico del Romanticismo puro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En la segunda parte del programa, la Orquesta Sinf\u00f3nica de S.L.P., bajo la direcci\u00f3n del Mtro. Jos\u00e9 Miramontes Zapata, interpreta la Primera Sinfon\u00eda en Do menor, Op.68, de Johannes Brahms.\u00a0\u00a0Se dice que\u00a0el profundo conocimiento que Brahms ten\u00eda de la m\u00fasica del pasado y su propio sentido de la responsabilidad art\u00edstica, le impidi\u00f3 componer sinfon\u00edas hasta muy tarde. A esta obra, por ejemplo, le llev\u00f3 al menos catorce a\u00f1os completarla (los primeros bocetos datan de 1862 y se estren\u00f3 el\u00a0\u00a04 de noviembre de 1876).\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Despu\u00e9s de la \u201cNovena\u201d, de Beethoven, en el verano de 1876 se estren\u00f3 el ciclo completo de \u201cEl Anillo de Nibelungo\u201d, de Wagner, obra que debiera certificar la evoluci\u00f3n de la sinfon\u00eda hacia la teatralidad. Sin embargo, es esta Primera Sinfon\u00eda, de Brahms, en la que recae el sobrenombre de la \u201cD\u00e9cima Sinfon\u00eda\u201d, al considerarse la primera obra que merec\u00eda el nombre de Sinfon\u00eda despu\u00e9s de las de Beethoven, seg\u00fan lo estim\u00f3\u00a0Hans von B\u00fclow,\u00a0compositor, pianista y uno de los m\u00e1s famosos directores de orquesta alemanes del siglo XIX, alumno de Richard Wagner y Franz Liszt.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esta obra Brahms hace claras referencias a las obras de los grandes compositores que le antecedieron, como Bach, Beethoven, Schubert, Shumann, etc., aunque con una mentalidad m\u00e1s cercana al siglo XX.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los bocetos para estos conciertos ya est\u00e1n a la venta en las taquillas del teatro y a trav\u00e9s de\u00a0<\/span><a href=\"http:\/\/www.ticketmania.mx\/\"><span style=\"font-weight: 400;\">www.ticketmania.mx<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participa la pianista austriaca Hanna Bachmann, quien se presenta en San Luis Potos\u00ed por primera vez. Este viernes 11 de<\/p>\n","protected":false},"author":2,"featured_media":10947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/10946"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=10946"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/10946\/revisions"}],"predecessor-version":[{"id":10948,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/10946\/revisions\/10948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/10947"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=10946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=10946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=10946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}