{"id":11045,"date":"2018-05-10T14:20:10","date_gmt":"2018-05-10T20:20:10","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=11045"},"modified":"2018-05-19T14:20:30","modified_gmt":"2018-05-19T20:20:30","slug":"seis-atletas-potosinos-a-los-juegos-mundiales-de-olimpiada-especial-2019","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/seis-atletas-potosinos-a-los-juegos-mundiales-de-olimpiada-especial-2019\/","title":{"rendered":"SEIS ATLETAS POTOSINOS A LOS JUEGOS MUNDIALES DE OLIMPIADA ESPECIAL 2019"},"content":{"rendered":"<ul>\n<li><strong>La sede del Mundial ser\u00e1 en Abu Dhabi, Emiratos \u00c1rabes del 14 al 21 de marzo del 2019<\/strong><\/li>\n<\/ul>\n<p>Un total de seis deportistas potosinos estar\u00e1n representando a M\u00e9xico en los Juegos Mundiales de Olimpiada Especial 2019 a celebrarse en Abu Dhabi, Emiratos \u00c1rabes; ser\u00e1n Martin Uriel Torres Y\u00e1\u00f1ez en Nataci\u00f3n, Juan Ignacio Cabrera Ram\u00edrez (deportista), Jos\u00e9 Tomas Ram\u00edrez Ugalde (Unificado) en Aguas Abiertas, Mar\u00eda Guadalupe L\u00f3pez Loredo en equitaci\u00f3n, Abiud Israel Olguin Vel\u00e1zquez en Levantamiento de Pesas e Irving Osiris Alem\u00e1n Duarte en Tenis.<\/p>\n<p>Los deportistas potosinos antes mencionados fueron elegidos por el consejo de Olimpiada Especial Nacional siendo San Luis Potos\u00ed el Estado que mas atletas aportara para este evento internacional dejando en claro el gran nivel competitivo que hay en nuestra delegaci\u00f3n.<\/p>\n<p>Los potosinos obtuvieron un gran desempe\u00f1o en los pasados Juegos Nacionales de Verano de Olimpiada Especial en la ciudad de Puebla en donde se obtuvo un total de 46 preseas entre las cuales fueron 25 de oro; 9 de plata y 12 de bronce lo que vali\u00f3 para que la Delegaci\u00f3n de San Luis Potos\u00ed fuera el Estado con mayor numero de atletas para el Mundial.<\/p>\n<p>Los seis atletas especiales se tendr\u00e1n que concentra el pr\u00f3ximo a\u00f1o para tomar parte en los Juegos Mundiales de Olimpiada Especial 2019 a celebrarse en Abu Dhabi, Emiratos \u00c1rabes del 13 al 21 de marzo del 2019.<\/p>\n<p>El presidente de la Olimpiada Especiales en San Luis Potos\u00ed Juan Pablo L\u00f3pez Corpus agradeci\u00f3 el apoyo recibido por las autoridades estatales quienes junto a los padres de los deportistas han logrado conseguir los boletos para representar a nuestro pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sede del Mundial ser\u00e1 en Abu Dhabi, Emiratos \u00c1rabes del 14 al 21 de marzo del 2019 Un total<\/p>\n","protected":false},"author":2,"featured_media":11046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11045"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=11045"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11045\/revisions"}],"predecessor-version":[{"id":11047,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11045\/revisions\/11047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/11046"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=11045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=11045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=11045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}