{"id":11048,"date":"2018-05-10T14:24:19","date_gmt":"2018-05-10T20:24:19","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=11048"},"modified":"2018-05-19T14:24:31","modified_gmt":"2018-05-19T20:24:31","slug":"homenaje-por-el-dia-de-las-madres-encabezo-el-gobernador-del-estado-en-el-jardin-de-tequis","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/homenaje-por-el-dia-de-las-madres-encabezo-el-gobernador-del-estado-en-el-jardin-de-tequis\/","title":{"rendered":"HOMENAJE POR EL D\u00cdA DE LAS MADRES ENCABEZ\u00d3 EL GOBERNADOR DEL ESTADO EN EL JARD\u00cdN DE TEQUIS"},"content":{"rendered":"<p>Un c\u00e1lido festejo por el D\u00eda de las Madres encabez\u00f3 el Gobernador del Estado en el jard\u00edn de Tequis, en donde luego de depositar una ofrenda floral y realizar una guardia de honor ante el monumento a la madre, reconoci\u00f3 el trabajo que las mujeres realizan diariamente en bien del progreso de San Luis Potos\u00ed y para el bienestar familiar.<\/p>\n<p>En entrevista con medios de comunicaci\u00f3n dijo que ellas son la base del n\u00facleo social que es la familia. Por ello les env\u00edo todo mi aprecio y mi felicitaci\u00f3n, pero tambi\u00e9n un reconocimiento por todo lo que contribuyen en el bienestar.<\/p>\n<p>Acompa\u00f1ado de la presidenta de la junta directiva del DIF Estatal, as\u00ed como del presidente del Club de Leones Jos\u00e9 Luis Jim\u00e9nez Ni\u00f1o y de la directora del Comit\u00e9 de Damas Leonas, Mar\u00eda Socorro Renter\u00eda de Jim\u00e9nez, ofrecieron un musical en el que participaron la rondalla del Colegio de Bachilleres n\u00famero 24 de Ciudad Valles y la Banda de M\u00fasica del Estado.<\/p>\n<p>Asimismo, las Ma\u00f1anitas fueron interpretadas por el mariachi El Rey para todas las asistentes encabezadas por Rosa Isela, originaria de Axtla de Terrazas y quien en esta ocasi\u00f3n represent\u00f3 simb\u00f3licamente a las madres potosinas que laboran en diversos centros de trabajo y en el hogar, al cuidado de su familia.<\/p>\n<p>Asimismo se llev\u00f3 a cabo un concierto con interpretaciones de la mezozoprano Beatriz Monta\u00f1o y la soprano Alejandra Carolina Rita Rubio a temas como Amor Eterno, de Juan Gabriel y La Media Vuelta de Jos\u00e9 Alfredo Jim\u00e9nez.<\/p>\n<p>Finalmente, alumnas de la Escuela de Artes y Oficios partieron varios pasteles que fueron obsequiados a los asistentes al evento.<\/p>\n<p><strong>ASISTE A FESTEJO DE MAESTRAS DE LA SECCI\u00d3N 26 DEL SNTE<\/strong><\/p>\n<p><strong>\u00a0<\/strong>El Gobernador del Estado acudi\u00f3 como invitado al festej\u00f3 del D\u00eda de las Madres de las maestras afiliadas a la Secci\u00f3n 26 del Sindicato Nacional de Trabajadores de la Educaci\u00f3n (SNTE), a quienes les expres\u00f3 que llevan consigo los dos t\u00edtulos m\u00e1s trascedentes y nobles de San Luis Potos\u00ed: ser docentes de ni\u00f1os y ni\u00f1as y ser madres.<\/p>\n<p>El mandatario estatal las felicit\u00f3 por el papel que desempe\u00f1an cotidianamente no solamente al frente de un sal\u00f3n de clases con sus alumnos y alumnas, sino tambi\u00e9n en sus hogares \u201cdonde inculcan valores y principios a sus hijas e hijos para ser personas de bien\u201d.<\/p>\n<p>En el evento que se llev\u00f3 a cabo en el Centro de Convenciones de San Luis Potos\u00ed, al que acudieron m\u00e1s de 1,300 docentes de nivel inicial y de primaria adheridas al SNTE, para disfrutar acompa\u00f1adas por sus familias de una velada musical.<\/p>\n<p>Asistieron los representantes sindicales de la Secci\u00f3n 26 del SNTE, encabezada por su secretario general y el secretario de Educaci\u00f3n del Gobierno del Estado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un c\u00e1lido festejo por el D\u00eda de las Madres encabez\u00f3 el Gobernador del Estado en el jard\u00edn de Tequis, en<\/p>\n","protected":false},"author":2,"featured_media":11049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11048"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=11048"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11048\/revisions"}],"predecessor-version":[{"id":11050,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11048\/revisions\/11050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/11049"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=11048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=11048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=11048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}