{"id":11218,"date":"2018-05-25T14:27:57","date_gmt":"2018-05-25T20:27:57","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=11218"},"modified":"2018-05-25T14:27:57","modified_gmt":"2018-05-25T20:27:57","slug":"ineficiente-alerta-de-genero-debido-a-falta-de-atencion-de-autoridades-legisladora-martha-orta-rodriguez","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/ineficiente-alerta-de-genero-debido-a-falta-de-atencion-de-autoridades-legisladora-martha-orta-rodriguez\/","title":{"rendered":"INEFICIENTE ALERTA DE G\u00c9NERO DEBIDO A FALTA DE ATENCI\u00d3N DE AUTORIDADES: LEGISLADORA MARTHA ORTA RODR\u00cdGUEZ."},"content":{"rendered":"<p>La violencia contra las mujeres sigue ocurriendo en San Luis Potos\u00ed porque las autoridades no atienden las medidas preventivas ni activan los protocolos establecidos oportunamente, lo que genera que sea ineficiente la Alerta de G\u00e9nero y que la vida de ellas siga estando en riesgo, se\u00f1al\u00f3 la legisladora Martha Orta Rodr\u00edguez.<\/p>\n<p>Lament\u00f3 que cada semana se sigan presentando hechos donde mujeres pierden la vida por diferentes causas, \u201cdebemos condenar la muerte de una joven a manos de su novio de una manera cruel y es un foco rojo que debe llamar a las autoridades a actuar oportunamente para evitar que sigan ocurriendo casos as\u00ed\u201d.<\/p>\n<p>La Alerta de G\u00e9nero de nada sirve si se queda en un marco enunciativo, se tiene que generar que haya verdaderas acciones para prevenir y sancionar la violencia contra las mujeres, que los fiscales y las agencias que atienden estos asuntos no minimicen las medidas cautelares, hay que trabajar en la prevenci\u00f3n, atenci\u00f3n, sanci\u00f3n y dar acompa\u00f1amiento a quienes son\u00a0 violentadas para que denuncien y que las autoridades asuman su responsabilidad, se\u00f1al\u00f3.<\/p>\n<p>Orta Rodr\u00edguez a\u00f1adi\u00f3 que son muchos los aspectos desde donde se debe combatir este problema, como es la coordinaci\u00f3n entre municipios donde fue decretada la Alerta de G\u00e9nero, porque la vida debe estar por encima de todo y las mujeres tienen el derecho de transitar en un estado libre, donde su vida no est\u00e9 en riesgo solo por el hecho de serlo.<\/p>\n<p>Un punto muy importante es la prevenci\u00f3n, hay violent\u00f3metros que se pueden distribuir para detectar si su pareja busca controlarles el uso de las redes sociales, o c\u00f3mo se visten, lo que es una se\u00f1al clara de que hay riesgos de violencia, se debe visibilizar esa situaci\u00f3n y si hay denuncia, atenderla de inmediato, dijo la legisladora.<\/p>\n<p>\u201cCuando una mujer acude a presentar una denuncia le preguntan si en realidad quiere presentar la denuncia y eso las desanima, porque se supone que si acuden a la autoridad es porque est\u00e1n dispuestas a denunciar pero las hacen dudar, ah\u00ed es cuando necesitan el apoyo, la protecci\u00f3n y que la autoridad ponga en funcionamiento toda su fuerza para protegerla\u201d, puntualiz\u00f3 la diputada Martha Orta.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La violencia contra las mujeres sigue ocurriendo en San Luis Potos\u00ed porque las autoridades no atienden las medidas preventivas ni<\/p>\n","protected":false},"author":2,"featured_media":10660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11218"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=11218"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11218\/revisions"}],"predecessor-version":[{"id":11219,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11218\/revisions\/11219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/10660"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=11218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=11218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=11218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}