{"id":11296,"date":"2018-05-10T07:33:35","date_gmt":"2018-05-10T13:33:35","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=11296"},"modified":"2018-05-30T07:34:59","modified_gmt":"2018-05-30T13:34:59","slug":"dotaran-de-herramientas-legales-a-los-presidentes-municipales","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/dotaran-de-herramientas-legales-a-los-presidentes-municipales\/","title":{"rendered":"DOTAR\u00c1N DE HERRAMIENTAS LEGALES A LOS PRESIDENTES MUNICIPALES"},"content":{"rendered":"<p>El Congreso del Estado dotar\u00e1 de herramientas legales a los presidentes municipales para que presupuestalmente hagan frente a los laudos laborales que agobian las finanzas municipales, a trav\u00e9s de una iniciativa de ley que ya fuer aprobada en la Comisi\u00f3n de Hacienda y est\u00e1 en revisi\u00f3n en la Comisi\u00f3n del Trabajo, inform\u00f3 el diputado Mariano Ni\u00f1o Mart\u00ednez.<\/p>\n<p>El objetivo es que en su Ley de Ingresos los ayuntamientos puedan incluir una partida presupuestal para que dispongan de recursos y eviten de esta manera tener que recurrir a solicitudes de cr\u00e9dito o peor a\u00fan, tomar dinero de otros rubros, cometiendo irregularidades que les generan observaciones en la Auditor\u00eda Superior del Estado, poniendo candados y estableciendo condiciones para el uso de ese presupuesto.<\/p>\n<p>El tema de los laudos laborales se ha convertido en un asunto complicado para los alcaldes, porque muchos de ellos desde que llegan a la administraci\u00f3n ya traen una carga enorme incluso de varios a\u00f1os y no se resuelven por los problemas presupuestales, de tal manera que un finiquito que pudo ser de 50 mil pesos se convierte hasta en 400 mil pesos en unos a\u00f1os y con riesgo de seguir creciendo.<\/p>\n<p>\u201cEs una bola de nieve que se traduce en cientos de miles de pesos y el municipio siempre pierde, porque el alcalde tiene que tomar dinero de otro rubro y a veces ni as\u00ed le alcanza, mientras tanto, va generando problemas de observaciones y el problema laboral sigue vigente, por eso es importante darle las herramientas legales para que pueda disponer de una partida y la maneje con absoluta responsabilidad\u201d.<\/p>\n<p>El diputado Mariano Ni\u00f1o a\u00f1adi\u00f3 que hay trabajadores que son despedidos por cuestiones pol\u00edticas, otros tienen la capacidad para quedarse pero no son aceptados, no se ponen de acuerdo en la liquidaci\u00f3n y el problema se va alargando a veces hasta con dolo para que el asunto dure a\u00f1os y as\u00ed, todo termina en laudos que son impagables o que afectan severamente las finanzas municipales.<\/p>\n<p>Expuso que los legisladores trabajaron y lo seguir\u00e1n haciendo en comisiones en base a una problem\u00e1tica real, con estad\u00edsticas de cada ayuntamiento y lo m\u00e1s probable es que pronto todo se resuelva para que los pr\u00f3ximos presidentes municipales puedan trabajar sin ning\u00fan problema de esta \u00edndole.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Congreso del Estado dotar\u00e1 de herramientas legales a los presidentes municipales para que presupuestalmente hagan frente a los laudos<\/p>\n","protected":false},"author":2,"featured_media":11297,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11296"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=11296"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11296\/revisions"}],"predecessor-version":[{"id":11298,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/11296\/revisions\/11298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/11297"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=11296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=11296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=11296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}