{"id":18760,"date":"2018-12-12T08:52:58","date_gmt":"2018-12-12T14:52:58","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=18760"},"modified":"2018-12-13T08:54:10","modified_gmt":"2018-12-13T14:54:10","slug":"se-fortaleceran-las-areas-responsables-en-el-combate-a-la-corrupcion","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/se-fortaleceran-las-areas-responsables-en-el-combate-a-la-corrupcion\/","title":{"rendered":"SE FORTALECER\u00c1N LAS \u00c1REAS RESPONSABLES EN EL COMBATE A LA CORRUPCI\u00d3N."},"content":{"rendered":"<p><strong>\u201cBUSCAREMOS QUE CUENTEN CON LOS RECURSOS NECESARIOS\u201d: DIP. MARITE HERN\u00c1NDEZ CORREA.<\/strong><\/p>\n<p>El Congreso del Estado, buscar\u00e1 fortalecer las \u00e1reas vinculadas al combate de la corrupci\u00f3n a trav\u00e9s de m\u00e1s recursos econ\u00f3micos dentro del Presupuesto de Egresos para el Ejercicio Fiscal 2019 del Gobierno del Estado, pues este es un compromiso al que se le debe poner una mayor atenci\u00f3n.<\/p>\n<p>La presidenta de la Comisi\u00f3n de Vigilancia de la LXII legislatura, diputada Marite Hern\u00e1ndez Correa, reconoci\u00f3 que a\u00fan falta mucho por hacer para establecer con mayor eficacia las acciones que permitan prevenir y sancionar los actos de corrupci\u00f3n.<\/p>\n<p>\u201cYo creo que es fundamental\u00a0 elevar el debate en torno al tema anticorrupci\u00f3n, as\u00ed como en la rendici\u00f3n de cuentas, el uso de los recursos p\u00fablicos, y las sanciones a quienes incurran en estas irregularidades\u201d, agreg\u00f3.<\/p>\n<p>Adem\u00e1s, dijo que durante la revisi\u00f3n y el an\u00e1lisis del proyecto presupuestal del Gobierno del Estado, los legisladores en su conjunto tendr\u00e1n que realizar un diagn\u00f3stico para darle prioridad a estos temas que son fundamentales y que buscan sancionar todo acto de corrupci\u00f3n que afecta el desarrollo de la administraci\u00f3n p\u00fablica.<\/p>\n<p>La legisladora Marite Hern\u00e1ndez, refrend\u00f3 su compromiso por analizar a fondo el Presupuesto de Egresos para el Ejercicio Fiscal 2019 del Gobierno del Estado, tomando en cuenta que es necesario impulsar un presupuesto equilibrado, pero bajo una perspectiva social que permita atender las principales necesidades de la poblaci\u00f3n m\u00e1s vulnerable.<\/p>\n<p>Sostuvo que el combate a la corrupci\u00f3n debe ser una prioridad para todos, \u201ces decir para los tres Poderes del Estado, donde se debe privilegiar la trasparencia, la rendici\u00f3n de cuentas y sobre todo, la claridad del destino y la aplicaci\u00f3n de los recursos p\u00fablicos\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cBUSCAREMOS QUE CUENTEN CON LOS RECURSOS NECESARIOS\u201d: DIP. MARITE HERN\u00c1NDEZ CORREA. El Congreso del Estado, buscar\u00e1 fortalecer las \u00e1reas vinculadas<\/p>\n","protected":false},"author":2,"featured_media":18761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18760"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=18760"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18760\/revisions"}],"predecessor-version":[{"id":18762,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18760\/revisions\/18762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/18761"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=18760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=18760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=18760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}