{"id":18783,"date":"2018-12-13T08:21:56","date_gmt":"2018-12-13T14:21:56","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=18783"},"modified":"2018-12-14T08:22:56","modified_gmt":"2018-12-14T14:22:56","slug":"trabajamos-juntos-para-sacar-adelante-a-nuestra-ninez-y-juventud-jm-carreras","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/trabajamos-juntos-para-sacar-adelante-a-nuestra-ninez-y-juventud-jm-carreras\/","title":{"rendered":"TRABAJAMOS JUNTOS PARA SACAR ADELANTE A NUESTRA NI\u00d1EZ Y JUVENTUD: JM CARRERAS"},"content":{"rendered":"<ul>\n<li style=\"font-weight: 400;\"><b>Mandatario Estatal realiza gira de trabajo por Villa de Arista y Venado<\/b><\/li>\n<li style=\"font-weight: 400;\"><b>Entrega acciones por m\u00e1s de 6.5 MDP.<\/b><\/li>\n<li style=\"font-weight: 400;\"><b>Visita a productores de programa caprino<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Villa de Arista.- Al entregar acciones en infraestructura educativa, electrificaci\u00f3n y apoyo a productores del campo por m\u00e1s de 6.5 millones de pesos, el Gobernador del Estado, Juan Manuel Carreras L\u00f3pez, asegur\u00f3 que el compromiso de su administraci\u00f3n es trabajar en conjunto para sacar adelante a nuestras ni\u00f1as, ni\u00f1os y adolescentes, esfuerzos que van de la mano con padres y madres de familia e instancias municipales. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El titular del Ejecutivo destac\u00f3 en este municipio, que es de vital importancia la suma de esfuerzos para lograr objetivos comunes, como es el fortalecimiento educativo, infraestructura e igualdad social, de ah\u00ed la importancia de integrar los programas de los tres niveles de gobierno para consolidar estas acciones. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En su participaci\u00f3n el Secretario de Educaci\u00f3n, Joel Ram\u00edrez D\u00edaz, explic\u00f3 que desde el arranque de la administraci\u00f3n que encabeza Carreras L\u00f3pez, se han destinado recursos en infraestructura, mejoramiento o equipamiento por 16 millones de pesos, en 38 acciones que van en beneficio de 61 planteles educativos de este municipio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al iniciar esta gira de trabajo, el jefe estatal visit\u00f3 el Centro de Atenci\u00f3n M\u00faltiple \u201cLouis Braille\u201d, donde se imparte educaci\u00f3n especial, en esta comunidad entreg\u00f3 el techado de la cancha, que tuvo una inversi\u00f3n de casi 700 mil pesos, se beneficia a m\u00e1s de 166 alumnos y alumnas de este municipio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el jard\u00edn de ni\u00f1os \u201cFrancisco I. Madero\u201d, Carreras L\u00f3pez reconoci\u00f3 el esfuerzo de los pap\u00e1s y mam\u00e1s en conjunto con la fuerza docente, para la rehabilitaci\u00f3n integral de este plantel, que tuvo una inversi\u00f3n de 678 mil pesos, que impacta a 216 estudiantes. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al entregar el proyecto de rehabilitaci\u00f3n de la escuela primaria \u201cEmiliano Zapata\u201d, el mandatario explic\u00f3 que es este plantel es de tiempo completo, que cuenta adem\u00e1s con comedor, de ah\u00ed la importancia de la inversi\u00f3n por 770 mil pesos, al ser una de las escuelas m\u00e1s grandes de Villa de Arista.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Despu\u00e9s entreg\u00f3 en la Telesecundaria \u201cVenustiano Carranza\u201d del ejido San El\u00edas, el aula did\u00e1ctica, donde se destinaron fondos por 730 mil pesos, en esta misma localidad arranc\u00f3 con el programa de electrificaci\u00f3n que tuvo una inversi\u00f3n por un mill\u00f3n 214 mil pesos. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lucero Mart\u00ednez, agradeci\u00f3 a nombre de toda la comunidad por la construcci\u00f3n del aula did\u00e1ctica, por el compromiso de esta administraci\u00f3n para fortalecer la infraestructura educativa, con el compromiso de mejorar la calidad de los planteles; en respuesta, indic\u00f3 que responder\u00e1n con el mismo empe\u00f1o y esfuerzo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Posteriormente, el Gobernador Estatal entreg\u00f3 40 acciones de vivienda en beneficio de igual n\u00famero de familias, programa que lleva a cabo la Secretar\u00eda de Desarrollo Social y Regional (SEDESORE), para este municipio se destinan cerca de dos millones de pesos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con el objetivo de impulsar el desarrollo de las familias de este municipio, el mandatario visit\u00f3 a productores beneficiados del programa caprino, a quienes les refrend\u00f3 el compromiso de su administraci\u00f3n para contribuir en el crecimiento de estos importantes esquemas, solo en Villa de Arista, la administraci\u00f3n estatal apoya a 20 capricultores, con corrales que tienen una inversi\u00f3n de 70 mil pesos, que se traduce en una inversi\u00f3n por un mill\u00f3n 400 mil pesos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al finalizar esta gira de trabajo, visit\u00f3 la comunidad de El Epazote en el municipio de Venado, arranc\u00f3 con la ampliaci\u00f3n de la electrificaci\u00f3n para esta localidad, aqu\u00ed se invirtieron recursos por un mill\u00f3n 200 mil pesos. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En esta gira de trabajo acompa\u00f1aron al mandatario estatal Mois\u00e9s Aurelio Arriaga Tovar, Presidente Municipal de Villa de Arriaga; Adalberto Mart\u00ednez Carrera, Coordinador de Desarrollo Social Municipal de Venado, as\u00ed como los secretarios de Educaci\u00f3n y Desarrollo Social y Regional, Joel Ram\u00edrez D\u00edaz y Alberto El\u00edas S\u00e1nchez; el Coordinador de Comunicaci\u00f3n Social de Gobierno del Estado, Ra\u00fal Camacho Mu\u00f1oz.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mandatario Estatal realiza gira de trabajo por Villa de Arista y Venado Entrega acciones por m\u00e1s de 6.5 MDP. Visita<\/p>\n","protected":false},"author":2,"featured_media":18784,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18783"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=18783"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18783\/revisions"}],"predecessor-version":[{"id":18785,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18783\/revisions\/18785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/18784"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=18783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=18783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=18783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}