{"id":18802,"date":"2018-12-13T09:43:27","date_gmt":"2018-12-13T15:43:27","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=18802"},"modified":"2018-12-14T09:56:09","modified_gmt":"2018-12-14T15:56:09","slug":"se-apoya-la-feria-de-la-salud-en-comunidades-de-villa-de-ramos","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/se-apoya-la-feria-de-la-salud-en-comunidades-de-villa-de-ramos\/","title":{"rendered":"SE APOYA LA FERIA DE LA SALUD EN COMUNIDADES DE VILLA DE RAMOS."},"content":{"rendered":"<p><strong>NECESARIO SUMAR ESFUERZOS PARA GARANTIZAR LA ATENCI\u00d3N M\u00c9DICA A TODA LA POBLACI\u00d3N: DIP. LAURA PATRICIA SILVA CELIS.<\/strong><\/p>\n<p>La diputada Laura Patricia Silva Celis, representante del Distrito IV Local, realiz\u00f3 en conjunto con el ayuntamiento de Villa de Ramos y la Secretar\u00eda de Salud del Estado, la Feria de la Salud en la comunidad del Zacat\u00f3n.<\/p>\n<p>En este evento se ofreci\u00f3 a la poblaci\u00f3n de la zona altiplano, diversas acciones para cuidado a la salud, m\u00f3dulos de vacunaci\u00f3n, informaci\u00f3n sobre salud reproductiva<\/p>\n<p>y planificaci\u00f3n familiar, detecci\u00f3n oportuna de enfermedades como diabetes mellitus, revisi\u00f3n en salud para adultos mayores, y nutrici\u00f3n y actividad f\u00edsica, entre otras actividades.<\/p>\n<p>La legisladora explic\u00f3 que con estos trabajos, se busca acercar todos los programas de prevenci\u00f3n en salud a los habitantes de la zona altiplano, por lo cual, se sumaron las acciones de la propia presidencia municipal con las autoridades de salud y que la poblaci\u00f3n pueda contar de manera directa con estos programas.<\/p>\n<p>\u201cSe hicieron llegar a la ciudadan\u00eda de esa comunidad diferentes servicios que ofrece la Secretaria de Salud para la prevenci\u00f3n de enfermedades, la aplicaci\u00f3n de vacunas, y detecci\u00f3n de VIH, y que queremos es que puedan conocer los diferentes servicios que se ofrecen en la Secretar\u00eda de Salud en el cuidado de su salud\u201d.<\/p>\n<p>La diputada indic\u00f3 que estas acciones que realiza, forman parte de las labores de vinculaci\u00f3n como representante de este sector con la poblaci\u00f3n, de manera que se puedan llevar beneficios para las comunidades m\u00e1s apartadas.<\/p>\n<p>\u201cEs una feria que pretendemos acercarnos a las comunidades y la sociedad de una manera m\u00e1s eficiente en cuanto a los servicios que podamos estar prestando y para que la gente conozca la relaci\u00f3n entre el Congreso a trav\u00e9s de mi persona como diputada local para que puedan tener un acceso m\u00e1s r\u00e1pido a las cuestiones de salud\u201d.<\/p>\n<p>Finalmente, Silva Celis se\u00f1al\u00f3 que se buscar\u00e1 ofrecer este tipo de eventos en diversos municipios del altiplano que conforman el IV Distrito Local.<\/p>\n<p>\u201cLa idea es que podamos hacer esta actividad en todo el distrito, empezamos en Villa de Ramos porque el presidente municipal r\u00e1pidamente nos dio las condiciones a trav\u00e9s de la presidencia del DIF municipal para ponernos de acuerdo, pero en el pr\u00f3ximo a\u00f1o, empezando vamos a estar trabajado en la misma din\u00e1mica en todo el distrito\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NECESARIO SUMAR ESFUERZOS PARA GARANTIZAR LA ATENCI\u00d3N M\u00c9DICA A TODA LA POBLACI\u00d3N: DIP. LAURA PATRICIA SILVA CELIS. La diputada Laura<\/p>\n","protected":false},"author":2,"featured_media":18803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18802"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=18802"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18802\/revisions"}],"predecessor-version":[{"id":18804,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18802\/revisions\/18804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/18803"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=18802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=18802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=18802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}