{"id":18819,"date":"2018-12-14T15:25:59","date_gmt":"2018-12-14T21:25:59","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=18819"},"modified":"2018-12-14T15:25:59","modified_gmt":"2018-12-14T21:25:59","slug":"personal-de-om-participa-en-certificacion-para-atencion-a-la-ciudadania","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/personal-de-om-participa-en-certificacion-para-atencion-a-la-ciudadania\/","title":{"rendered":"PERSONAL DE OM PARTICIPA EN CERTIFICACI\u00d3N PARA ATENCI\u00d3N A LA CIUDADAN\u00cdA"},"content":{"rendered":"<ul>\n<li><strong>Comprende la alineaci\u00f3n para la certificaci\u00f3n EC-0105, Atenci\u00f3n al Ciudadano en el Sector P\u00fablico.<\/strong><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong>Con el objetivo de ampliar la cobertura del Consejo Nacional de Normalizaci\u00f3n y Certificaci\u00f3n de Competencias Laborales, (CONOCER) a trav\u00e9s de la acreditaci\u00f3n de nuevos prestadores de servicio, el personal de la Direcci\u00f3n de Desarrollo Humano de la Oficial\u00eda Mayor, lleva a cabo el proceso de alineaci\u00f3n para la certificaci\u00f3n EC-0105, Atenci\u00f3n al Ciudadano en el Sector P\u00fablico.<\/p>\n<p>El prop\u00f3sito est\u00e1ndar de competencia sirve como referente para la evaluaci\u00f3n y certificaci\u00f3n de las personas que prestan un servicio de atenci\u00f3n personalizada al ciudadano en el sector p\u00fablico, desde la detecci\u00f3n de las necesidades del trabajo la gesti\u00f3n y procesamiento de la informaci\u00f3n.<\/p>\n<p>Esta alineaci\u00f3n\u00a0 se desarroll\u00f3 en el Auditorio \u201cPedro Antonio de los Santos\u201d ubicado en la planta alta del Palacio de Gobierno, donde los participantes buscan como puntos fundamentales incrementar la certificaci\u00f3n de competencias de las personas, alcanzar la satisfacci\u00f3n de los postulantes para Prestadores de Servicios, alcanzar la satisfacci\u00f3n de los usuarios, en relaci\u00f3n con la emisi\u00f3n de certificados y promover la agenda de capital humano para la competitividad.<\/p>\n<p>El instructor fue Humberto Adri\u00e1n D\u00edaz, quien proviene del Sistema Estatal para el Desarrollo Integral de la Familia (Dif), explic\u00f3 que el perfil del Est\u00e1ndar de Competencia es la atenci\u00f3n del ciudadano en el sector p\u00fablico con los siguientes elementos: Detectar las necesidades de servicio requerido por el ciudadano.\u00a0 Gestionar el servicio requerido por el ciudadano. Procesar documentaci\u00f3n del servicio proporcionado al ciudadano.<\/p>\n<p>En este sentido, el titular de la Direcci\u00f3n de Desarrollo Humano, Francisco Javier Escudero Villa, indic\u00f3 que se trabaja intensamente para mejorar la alineaci\u00f3n de la oferta educativa, con los conocimientos, habilidades, destrezas y actitudes de las personas, adquiridas en el trabajo o a lo largo de su vida, con certificaciones\u00a0 oficiales.<\/p>\n<p>Los criterios de evaluaci\u00f3n contempla el siguiente desempe\u00f1o: Se presenta ante el ciudadano, proporcionando su nombre, aplica el protocolo de inicio determinado por la instituci\u00f3n que presta el servicio, y se dirige al ciudadano con un lenguaje claro, preciso, fluido sin utilizar modismos, muletillas y t\u00e9rminos t\u00e9cnicos. Obtiene informaci\u00f3n del servicio que solicita el ciudadano, preguntando que servicio o tr\u00e1mite requiere, solicitando la informaci\u00f3n datos faltantes del servicio\/tr\u00e1mite que solicita de acuerdo con los lineamientos de la instituci\u00f3n.<\/p>\n<p>Obtiene informaci\u00f3n institucional sobre el servicio solicitado por el ciudadano: de acuerdo con los lineamientos establecidos por la instituci\u00f3n. Revisando en fuentes internas\/externas de acuerdo con las necesidades expresadas por el ciudadano. Buscar en fuentes documentales f\u00edsicas\/electr\u00f3nicas, acordes a las necesidades expresadas por el ciudadano.<\/p>\n<p>Confirmar el requerimiento hecho por el ciudadano, proporcionando informaci\u00f3n de acuerdo a los lineamientos de la dependencia que permitan clarificar las necesidades u obligaciones para efectuar su servicio.<\/p>\n<p>Con el EC-0105 Atenci\u00f3n al ciudadano en el sector p\u00fablico, se busca que la Direcci\u00f3n de Desarrollo Humano de la Oficial\u00eda Mayor, logre la certificaci\u00f3n proporcionando a la sociedad potosina los servicios de atenci\u00f3n con calidad y calidez, que es una de las instrucciones primarias que dio el Oficial Mayor, El\u00edas Pesina Rodr\u00edguez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comprende la alineaci\u00f3n para la certificaci\u00f3n EC-0105, Atenci\u00f3n al Ciudadano en el Sector P\u00fablico. \u00a0Con el objetivo de ampliar la<\/p>\n","protected":false},"author":2,"featured_media":18820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18819"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=18819"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18819\/revisions"}],"predecessor-version":[{"id":18821,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18819\/revisions\/18821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/18820"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=18819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=18819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=18819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}