{"id":18893,"date":"2018-12-15T15:26:34","date_gmt":"2018-12-15T21:26:34","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=18893"},"modified":"2018-12-15T15:26:34","modified_gmt":"2018-12-15T21:26:34","slug":"hospital-general-de-ciudad-valles-autorizado-para-trasplantes-de-rinon","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/hospital-general-de-ciudad-valles-autorizado-para-trasplantes-de-rinon\/","title":{"rendered":"HOSPITAL GENERAL DE CIUDAD VALLES AUTORIZADO PARA TRASPLANTES DE RI\u00d1\u00d3N"},"content":{"rendered":"<ul>\n<li><strong>Solo estaba autorizado para la extracci\u00f3n de \u00f3rganos, ahora podr\u00e1 trasplantar ri\u00f1\u00f3n para pacientes huastecos en lista de espera de este \u00f3rgano.<\/strong><\/li>\n<\/ul>\n<p>La Secretar\u00eda de Salud del estado recibi\u00f3 la Autorizaci\u00f3n Sanitaria de COFEPRIS para que el Hospital General de Ciudad Valles pueda realizar procesos de trasplante en la modalidad de Ri\u00f1\u00f3n, ya que s\u00f3lo estaba autorizado para la extracci\u00f3n de \u00f3rganos dio a conocer la doctora M\u00f3nica Liliana Rangel Mart\u00ednez, Secretaria de Salud, quien detall\u00f3 que hace meses se solicit\u00f3 a la COFEPRIS, la autorizaci\u00f3n toda vez que se hab\u00edan estado cumpliendo todos los protocolos en materia de extracci\u00f3n de \u00f3rganos, y a la par cumpliendo con procesos, capacitaci\u00f3n de personal y equipamiento.<\/p>\n<p>\u201cEsto es una gran noticia, ya que ahora el ri\u00f1\u00f3n que es el \u00f3rgano m\u00e1s requerido en materia de trasplante, ya no va a tener que ser enviado a la capital, y el equipo especializado del hospital podr\u00e1 trasplantarlo a pacientes de la huasteca que est\u00e9n en lista de espera y lo necesiten\u201d, inform\u00f3 M\u00f3nica Liliana Rangel.<\/p>\n<p>Agreg\u00f3 que esta importante autorizaci\u00f3n implica que el hospital podr\u00e1 tomar decisiones en su Comit\u00e9 interno, podr\u00e1 asignar los \u00f3rganos que reciban y tambi\u00e9n los que se generen ah\u00ed mismo basado en la lista de espera. Tendr\u00e1n protocolo para estudiar a los pacientes para realizar Trasplantes, asimismo solicitar \u00abasignaci\u00f3n prioritaria\u00bb en la que se puede acceder a nivel nacional a un \u00f3rgano en caso que se requiera por la gravedad del paciente.<\/p>\n<p>\u201cEs muy importante porque se trata del Hospital m\u00e1s importante de la huasteca, mismo que tendr\u00e1 acceso al registro nacional de trasplantes, para inscribir pacientes y comenzar, tanto a trasplantar de donantes vivos y donantes en muerte cerebral del propio hospital, c\u00f3mo a recibir \u00f3rganos de otros hospitales dentro y fuera del estado\u201d, dio a conocer la funcionaria de salud.<\/p>\n<p>La Secretaria de Salud dijo que durante este a\u00f1o el HG de Ciudad Valles se estuvo capacitando el personal y fortaleciendo instalaciones id\u00f3neas para la realizaci\u00f3n de trasplante renal, a trav\u00e9s de la coordinaci\u00f3n del Centro Estatal de Trasplantes (CETRA).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solo estaba autorizado para la extracci\u00f3n de \u00f3rganos, ahora podr\u00e1 trasplantar ri\u00f1\u00f3n para pacientes huastecos en lista de espera de<\/p>\n","protected":false},"author":2,"featured_media":18894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18893"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=18893"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18893\/revisions"}],"predecessor-version":[{"id":18895,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/18893\/revisions\/18895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/18894"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=18893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=18893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=18893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}