{"id":20016,"date":"2019-01-13T16:53:34","date_gmt":"2019-01-13T22:53:34","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=20016"},"modified":"2019-01-13T16:53:36","modified_gmt":"2019-01-13T22:53:36","slug":"exposiciones-permanentes-y-temporales-en-el-centro-cultural-de-real-de-catorce-para-iniciar-el-2019","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/exposiciones-permanentes-y-temporales-en-el-centro-cultural-de-real-de-catorce-para-iniciar-el-2019\/","title":{"rendered":"EXPOSICIONES PERMANENTES Y TEMPORALES EN EL CENTRO CULTURAL DE REAL DE CATORCE PARA INICIAR EL 2019"},"content":{"rendered":"\n<p>Para iniciar el 2019, se cuentan\ncon varias exposiciones en el Centro Cultural de Real de Catorce, que pueden\ndisfrutar tanto visitantes como residentes, y que se ubica en este Pueblo\nM\u00e1gico del mismo nombre.<\/p>\n\n\n\n<p>El Director del Centro Cultural\nde Real de Catorce, Sa\u00fal Sauceda Covarrubias, invita al p\u00fablico en general al\nvisitar este espacio ubicado en la Zona Altiplano, pues al momento \u201cse cuenta\ncon 6 exposiciones tanto permanentes como temporales, con un costo de acceso\nm\u00ednimo\u201d<\/p>\n\n\n\n<p>Este Centro Cultural, bajo la\ntutela de la Secretar\u00eda de Cultura, tiene el objetivo de promover, difundir y\nacrecentar las expresiones de la cultura en esta regi\u00f3n del estado.<\/p>\n\n\n\n<p>El funcionario detall\u00f3 cada una\nde las exposiciones que en este momento se encuentran abiertas al p\u00fablico \u201cla\nprimera es \u201cCulturas de un cactus Sagrado\u201d que muestra una costumbre que ha\ntrascendido a nuestros antepasados. Los huicholes comenzaron a ir a Wirikuta,\nReal de Catorce, quienes han mantenido esta tradici\u00f3n viva. Wirikuta es la\ntierra sagrada del peyote, a donde vienen los ancestros del oriente y donde\nnace la luz del padre sol Tayao en el cerro del quemado. Rumbo al oriente de\ndonde proviene la vida, donde mora Tamatz Kallamauri, el venado Azul.\u201d<\/p>\n\n\n\n<p>Otra exposici\u00f3n es la \u201cColecci\u00f3n\nde Arte Sacro del Padre Jos\u00e9 Robledo\u201d&nbsp;que son b\u00e1sicamente \u201crecuerdos\ngrabados en los corazones de todos los catorce\u00f1os que compartieron su estad\u00eda y\nel trabajo a favor del rescate hist\u00f3rico del legendario&nbsp;<em>Real<\/em>,\nhaci\u00e9ndolo renacer de las sombras del olvido. A pesar de los contratiempos y\ndificultades, compagino su trabajo espiritual y social de manera sorprendente,\nal lograr la uni\u00f3n de su ministerio con las autoridades civiles y trabajando en\nconjunto para dar a conocer esta hermosa ciudad.\u201d<\/p>\n\n\n\n<p>Sauceda Covarrubias invita a\ndisfruta tambi\u00e9n de la muestra de \u201cFotograf\u00eda Antigua\u201d unacolecci\u00f3n\nde fotograf\u00edas de personas catorce\u00f1as, donde \u201cla esencia de Real de Catorce en\nsus tiempos de anta\u00f1o quedaron plasmadas en fotograf\u00edas. Desde familias de\nmayor influencia en la \u00e9poca de bonanza, hasta la arquitectura que reflejaba al\nque en ese entonces fue uno de los principales centros mineros del pa\u00eds.\u201d<\/p>\n\n\n\n<p>Se \u201cmuestran im\u00e1genes de un\npueblo minero y la visita a este lugar de Porfirio D\u00edaz en su tiempo\npresidencial, fotograf\u00edas de las minas de Santa Ana, Pur\u00edsima Dolores Trompeta,\nt\u00fanel de Ogarrio y haciendas de beneficio; vida pol\u00edtica y actividades sociales\ndel pueblo de catorce en temporada de fiestas patrias, sal\u00f3n de cabildo,\nalgunos presidentes municipales y la inauguraci\u00f3n de la primera toma de agua en\nestaci\u00f3n de Catorce.\u201d<\/p>\n\n\n\n<p>En cuanto a algunos aspectos,\ncomo la vida religiosa de esta comunidad \u201cse cuenta con fotograf\u00edas sobre la fe\nmostrada a la imagen de San Francisco de As\u00eds, a la patrona de la iglesia\nprincipal, la virgen de Santamar\u00eda de la Pur\u00edsima Concepci\u00f3n y la virgen de\nGuadalupe; adem\u00e1s de varios grupos religiosos, tambi\u00e9n existen autorretratos\nque muestran a varias familias del pueblo con aspectos caracter\u00edsticos a la\nsociedad de aquellos a\u00f1os.\u201d<\/p>\n\n\n\n<p>Existen en esta exposici\u00f3n,\nregistros de las \u201cactividades sociales de Real de Catorce, im\u00e1genes que\nmuestran el aspecto social, educativo y distracciones que el pueblo ten\u00eda como\nrecreaci\u00f3n, as\u00ed mismo, escuelas que hab\u00eda hacia 1900, de un grupo de vigilancia\nencargada de la seguridad, la oficina de correos y la fotograf\u00eda del tranv\u00eda\nel\u00e9ctrico que serv\u00eda para cruzar el t\u00fanel.\u201d<\/p>\n\n\n\n<p>Y por \u00faltimo, &nbsp;en esta\nexposici\u00f3n se cuenta con fotograf\u00edas panor\u00e1micas la Estaci\u00f3n de Catorce con su\nplaza, el camino del cerro trozado y el trabajo de guayuleros en esta zona, una\nmuestra de c\u00f3mo estaba la plaza de armas, y la iglesia hacia los a\u00f1os de 1920 y\nla festividad de la comunidad de El Potrero.<\/p>\n\n\n\n<p>Una colecci\u00f3n muy importante la\nque tiene que ver con el origen de este Centro Cultural y es que fue la \u201cCasa\nde la Moneda de M\u00e9xico\u201d, por lo que una exposici\u00f3n nos muestra una \u201csimulaci\u00f3n\ndel proceso de hacer una moneda, fotograf\u00edas que destallan paso a paso c\u00f3mo es\nla elaboraci\u00f3n del metal con valor que a diario usamos y que ha tenido un\ntrabajo importante en la sociedad; as\u00ed como de los objetos que se utilizaban\npara llevar a cabo dicha tarea.\u201d<\/p>\n\n\n\n<p>En este espacio, se cuenta con\nuna muestra numism\u00e1tica de una valiosa colecci\u00f3n de monedas conmemorativas al\nCentenario de la Revoluci\u00f3n Mexicana con monedas de $5 pesos y medallas\nconmemorativas a esa fecha tan importante; del mismo modo existen en exhibici\u00f3n\nmonedas que conmemoran el Bicentenario de la Independencia de M\u00e9xico con\nmonedas de $100 que contienen un resello de los escudos de armas de cada\nestado.<\/p>\n\n\n\n<p>Se muestra al p\u00fablico \u201cuna\ncolecci\u00f3n importante de medallas y galardones que se hacen en la Casa de Moneda\nde M\u00e9xico y sirven para premiar y\/o reconocer un gran hecho y es un honor su\nentrega.\u201d<\/p>\n\n\n\n<p>Finalmente, apunt\u00f3 el Director de\neste espacio, Sa\u00fal Sauceda que \u201cen cuanto a exposiciones temporales se cuenta\ncon una&nbsp;<em>Colecci\u00f3n de pinturas Charly Tomorrow y Cora Van<\/em>, que son\npinturas al \u00f3leo de estos artistas alemanes, ahora residentes del pueblo m\u00e1gico\nde Real de Catorce, adem\u00e1s, en conmemoraci\u00f3n al XXVI Aniversario del Archivo\nHist\u00f3rico del estado de Zacatecas, se constituy\u00f3 una exposici\u00f3n de 12\nlitograf\u00edas originales realizadas en el taller de Vetagr\u00e1fica. La t\u00e9cnica\nutilizada se hac\u00eda desde d\u00e9cadas anteriores, grabado en piedra.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para iniciar el 2019, se cuentan con varias exposiciones en el Centro Cultural de Real de Catorce, que pueden disfrutar<\/p>\n","protected":false},"author":2,"featured_media":20017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/20016"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=20016"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/20016\/revisions"}],"predecessor-version":[{"id":20018,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/20016\/revisions\/20018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/20017"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=20016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=20016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=20016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}