{"id":20027,"date":"2019-01-12T17:12:32","date_gmt":"2019-01-12T23:12:32","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=20027"},"modified":"2019-01-13T17:13:03","modified_gmt":"2019-01-13T23:13:03","slug":"busca-diputado-que-haya-becas-al-100-por-ciento-para-alumnos-destacados-de-diversos-niveles-2","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/busca-diputado-que-haya-becas-al-100-por-ciento-para-alumnos-destacados-de-diversos-niveles-2\/","title":{"rendered":"BUSCA DIPUTADO QUE HAYA BECAS AL 100 POR CIENTO PARA ALUMNOS DESTACADOS DE DIVERSOS NIVELES"},"content":{"rendered":"\n<p>Comisiones al interior del Congreso del Estado, analizan\nla inici\u00e1tica de reforma a la Ley de Educaci\u00f3n del Estado presentada por el\ndiputado C\u00e1ndido Ochoa Rojas. En la que se promueve otorgar becas del 100%\n(cien por ciento) a aquellos alumnos destacados del Estado, se encuentren en\nescuelas p\u00fablicas o privadas, institutos educativos, universidades, p\u00fablicas o\nprivadas, para as\u00ed\u0301 seguir apoyando a que la educaci\u00f3n y el pa\u00eds vaya creciendo\ny fortaleciendo. <\/p>\n\n\n\n<p>La iniciativa contempla otorgar becas completas a todos\nlos alumnos que cuenten con un promedio de 9.5 (nueve punto cinco) en adelante,\ny que dicha beca no se le niegue a ninguno de estos, ya que las que actualmente\nse otorgan no son para todos los que las solicitan, si no que se escogen de los\nque la solicitan a unos cuantos.<\/p>\n\n\n\n<p>La educaci\u00f3n, es sin lugar a duda la actividad m\u00e1s importante\npara el desarrollo del ser humano y las naciones. De ah\u00ed\u0301 que la iniciativa\nest\u00e1 comprometida con la realidad para hacer valer los derechos de los\nestudiantes del Estado de San Luis Potos\u00ed\u0301.<\/p>\n\n\n\n<p>El diputado C\u00e1ndido Ochoa se\u00f1al\u00f3 que la educaci\u00f3n\nproporciona los conocimientos, y potencia las habilidades y destrezas de la\ncomunidad estudiantil. Y es la misma educaci\u00f3n la que permite la inclusi\u00f3n a la\nactividad laboral y econ\u00f3mica del pa\u00eds.<\/p>\n\n\n\n<p>\u201cEsta iniciativa destaca el apoyo a la educaci\u00f3n, ya que\ncon anterioridad la principal meta del Estado era llevar la educaci\u00f3n a todos\nlos rincones del pa\u00eds, esta meta ya fue casi lograda. Pero hoy en d\u00eda no solo\nse necesita una buena infraestructura en escuelas, buenos docentes en todos los\nniveles de educaci\u00f3n y programas de estudio. Hoy se cuestiona<\/p>\n\n\n\n<p>sobre si el contenido de la educaci\u00f3n es suficiente y\nrelevante para la sociedad de M\u00e9xico que est\u00e1 en v\u00edas de desarrollo\u201d.<\/p>\n\n\n\n<p>Abund\u00f3 que \u201cla raz\u00f3n de estos cuestionamientos es que\ntodos los pa\u00edses debido a la globalizaci\u00f3n, cada vez est\u00e1n en constante preparaci\u00f3n\nsobre todo aquellos pa\u00edses desarrollados, esto se debe a que la poblaci\u00f3n debe\nestar m\u00e1s preparada para desempe\u00f1arse competentemente en las diferentes\nactividades productivas de la naci\u00f3n y as\u00ed\u0301 la poblaci\u00f3n tenga un mayor nivel\nde vida, con menos desigualdades sociales y econ\u00f3micas\u201d.<\/p>\n\n\n\n<p>Puntualiz\u00f3 que \u201ccon estos y otros motivos que contiene la\npresente iniciativa, quedar\u00eda plasmado en nuestras leyes el reconocimiento de\nlos estudiantes de excelencia\u201d. La iniciativa se encuentra en an\u00e1lisis en\ncomisiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comisiones al interior del Congreso del Estado, analizan la inici\u00e1tica de reforma a la Ley de Educaci\u00f3n del Estado presentada<\/p>\n","protected":false},"author":2,"featured_media":20028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/20027"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=20027"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/20027\/revisions"}],"predecessor-version":[{"id":20029,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/20027\/revisions\/20029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/20028"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=20027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=20027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=20027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}