{"id":48067,"date":"2022-10-12T15:14:00","date_gmt":"2022-10-12T21:14:00","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=48067"},"modified":"2022-10-19T15:15:40","modified_gmt":"2022-10-19T21:15:40","slug":"gobernador-ricardo-gallardo-esta-terminando-con-la-desigualdad-social","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/gobernador-ricardo-gallardo-esta-terminando-con-la-desigualdad-social\/","title":{"rendered":"GOBERNADOR RICARDO GALLARDO EST\u00c1 TERMINANDO CON LA DESIGUALDAD SOCIAL"},"content":{"rendered":"\n<p>El Gobierno de San Luis Potos\u00ed, encabezado por Ricardo Gallardo Cardona, est\u00e1 terminando con la desigualdad social, porque adem\u00e1s de atender a\u00f1ejas peticiones que quedaron olvidadas por la \u201cherencia maldita\u201d, mantiene un acercamiento con la gente como nunca se hab\u00eda visto, aseguraron habitantes de Soledad de Graciano S\u00e1nchez, durante el arranque de los trabajos de rehabilitaci\u00f3n con concreto hidr\u00e1ulico de la avenida Valent\u00edn Amador.<\/p>\n\n\n\n<p>El Mandatario Estatal se mantuvo rodeado de personas de las colonias El Polvor\u00edn, Hogares Ferrocarrileros y de vecinos que tienen sus casas sobre esta importante arteria, la cual se mantuvo desatendida por muchos a\u00f1os, seg\u00fan lo confirm\u00f3 la se\u00f1ora Benita Huerta Hern\u00e1ndez. \u201cLa verdad es que la obra ya era muy necesaria y hac\u00eda falta un Gobernador que adem\u00e1s trabaja con programas sociales que son de mucho apoyo, porque la situaci\u00f3n que estamos atravesando es dif\u00edcil\u201d, dijo.<\/p>\n\n\n\n<p>Tambi\u00e9n Nicol\u00e1s Santos Segura, destac\u00f3 que el Gobierno que encabeza Ricardo Gallardo, est\u00e1 llevando los beneficios para todas y todos, sin importar colores o partidos pol\u00edticos y adem\u00e1s, mediante las obras de pavimentaci\u00f3n y los apoyos, busca acabar con la desigualdad social. \u201cLe agradecemos de antemano porque trae el desarrollo sin mirar colores, sin mirar partidos, sin distinci\u00f3n alguna, lo trae para todos y que bueno que nuestro Gobernador est\u00e9 acabando con tanta desigualdad social, porque le est\u00e1 dando lo que merece a la juventud, a los estudiantes, a la clase trabajadora, nos est\u00e1 favoreciendo y le agradecemos que nos haya tomado en cuenta\u201d, expres\u00f3.<\/p>\n\n\n\n<p>\u201cEstoy muy agradecida con el Gobernador por esta labor tan buena que est\u00e1 haciendo y que nos tome en cuenta, ya hac\u00eda falta la obra, desde hace 40 a\u00f1os que se hizo esta avenida, entonces ahorita s\u00ed est\u00e1 muy deteriorada y ahora s\u00ed va a ser m\u00e1s segura va a estar m\u00e1s iluminada y mis respetos para \u00e9l, porque es un Gobernador que ha hecho lo que nadie\u201d, se\u00f1al\u00f3 Rosa Mar\u00eda Beltr\u00e1n de La Paz, quien tiene su domicilio en la avenida Valent\u00edn Amador.<\/p>\n\n\n\n<p>Finalmente, la se\u00f1ora Laura del Carmen Otero, quien lleva muchos a\u00f1os habitando en Soledad de Graciano S\u00e1nchez, se mostr\u00f3 contenta con el cambio que han experimentado las colonias y en general todo el municipio, pues asegur\u00f3 que, por primera vez, hay un Gobernador que los voltea a ver y escucha, \u201cmagn\u00edfico, una gran persona porque nos ha visto, en realidad el cambio se ha visto todo \u00e9l y su gente que colabora, estamos muy agradecidos por las ayudas, mis respetos, todos le agradecemos todo lo que hace por Soledad, por San Luis y por todos sus municipios\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de San Luis Potos\u00ed, encabezado por Ricardo Gallardo Cardona, est\u00e1 terminando con la desigualdad social, porque adem\u00e1s de<\/p>\n","protected":false},"author":1,"featured_media":48068,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/48067"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=48067"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/48067\/revisions"}],"predecessor-version":[{"id":48069,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/48067\/revisions\/48069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/48068"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=48067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=48067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=48067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}