{"id":48070,"date":"2022-10-13T15:15:00","date_gmt":"2022-10-13T21:15:00","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=48070"},"modified":"2022-10-19T15:18:15","modified_gmt":"2022-10-19T21:18:15","slug":"moderniza-ricardo-gallardo-a-san-luis-potosi-con-nuevo-puente-atirantado-en-cactus","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/moderniza-ricardo-gallardo-a-san-luis-potosi-con-nuevo-puente-atirantado-en-cactus\/","title":{"rendered":"MODERNIZA RICARDO GALLARDO A SAN LUIS POTOS\u00cd CON NUEVO PUENTE ATIRANTADO EN CACTUS"},"content":{"rendered":"\n<p>El proceso de modernizaci\u00f3n y transformaci\u00f3n de San Luis Potos\u00ed que arranc\u00f3 con el Gobierno del cambio se fortalece, luego de que este jueves, el Gobernador del Estado Ricardo Gallardo Cardona, inici\u00f3 la construcci\u00f3n del Puente Superior Vehicular Atirantado sobre carretera a Rioverde, avenida Cactus a Ignacio Zaragoza en Soledad de Graciano S\u00e1nchez, con una inversi\u00f3n cercana a los 390 millones de pesos, que beneficiar\u00e1 a 250 mil usuarios y que fortalecer\u00e1 la movilidad de la zona.<\/p>\n\n\n\n<p>Ante cientos de vecinos y colonos, el Jefe del Ejecutivo Estatal, anunci\u00f3 que para Soledad el cambio ser\u00e1 verdadero, tras a\u00f1os de permanecer en el olvido gracias a la omisi\u00f3n de administraciones estatales anteriores. Por ello, anunci\u00f3 que se aumentar\u00e1 de 700 a mil millones de pesos el presupuesto para consolidar diversos proyectos de infraestructura que encaminen a este municipio a la modernidad. El Gobernador potosino llam\u00f3 a las y los soledenses a ponerse de acuerdo para que este tramo deje de conocerse como carretera a Rioverde y se convierta en un bulevar con un nuevo nombre.<\/p>\n\n\n\n<p>\u201cEso es lo que queremos, que sus casas sean las que suban de precio y no las de los dem\u00e1s, este puente es reflejo del nuevo Gobierno, de dar modernidad donde no lo hab\u00eda, capacidad de gesti\u00f3n donde no la hab\u00eda, pero sobre todo ganas de trabajar y de cambiar a San Luis Potos\u00ed, hab\u00edamos hecho un compromiso de darle a Soledad 300 a 800 millones en este a\u00f1o, pero hoy vengo a cambiar ese compromiso y subirlo a mil millones porque ustedes lo necesitan\u201d, expres\u00f3 el Mandatario Estatal.<\/p>\n\n\n\n<p>El se\u00f1or Mariano Torres, vecino de Hacienda los Morales, agradeci\u00f3 al Gobernador Ricardo Gallardo, por el enorme apoyo a la zona oriente, que por a\u00f1os necesitaba de la intervenci\u00f3n. \u201cEsta obra era muy necesaria debido a que la zona oriente ha crecido bastante en los \u00faltimos a\u00f1os, no solo las obras sino tambi\u00e9n los beneficios sociales que usted ha prometido, los est\u00e1 cumpliendo a cabalidad y eso habla muy bien de un Gobernador que se compromete con los ciudadanos y que cumple, con esto, nos va a dar una gran vialidad para salir de aqu\u00ed a nuestros trabajos\u201d, manifest\u00f3.<\/p>\n\n\n\n<p>El proyecto es un concepto moderno que se desarrollar\u00e1 en un tramo de 1.3 kil\u00f3metros, contemplando ambos sentidos con accesos a rampas de puente y tres carriles en puente y dos en laterales; con el proceso constructivo se contemplan intervenciones en sistema hidr\u00e1ulico-sanitario, terracer\u00edas, estructuras, pavimentos, alumbrado p\u00fablico, se\u00f1alamientos, trabajos generales y semaforizaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proceso de modernizaci\u00f3n y transformaci\u00f3n de San Luis Potos\u00ed que arranc\u00f3 con el Gobierno del cambio se fortalece, luego<\/p>\n","protected":false},"author":1,"featured_media":48071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/48070"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=48070"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/48070\/revisions"}],"predecessor-version":[{"id":48072,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/48070\/revisions\/48072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/48071"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=48070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=48070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=48070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}