{"id":8866,"date":"2018-03-06T08:07:05","date_gmt":"2018-03-06T14:07:05","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=8866"},"modified":"2018-03-07T08:12:45","modified_gmt":"2018-03-07T14:12:45","slug":"empresas-de-transporte-deberan-cumplir-con-todas-las-certificaciones-permisos-y-licencias","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/empresas-de-transporte-deberan-cumplir-con-todas-las-certificaciones-permisos-y-licencias\/","title":{"rendered":"EMPRESAS DE TRANSPORTE   DEBER\u00c1N CUMPLIR CON TODAS LAS CERTIFICACIONES, PERMISOS Y LICENCIAS."},"content":{"rendered":"<p>A propuesta del diputado Sergio Enrique Desfassiux Cabello, el Poder Legislativo aprob\u00f3 un punto de acuerdo para exhortar a los titulares de las secretar\u00edas de Comunicaciones y Transportes, Ramiro Robledo L\u00f3pez; del Trabajo y Previsi\u00f3n Social, Manuel Lozano Nieto; y de Desarrollo Econ\u00f3mico de Gobierno del Estado, Gustavo Puente Orozco, que \u00a0tomen las medidas necesarias para que exhorten a las empresas de la Zona Industrial a que contraten empresas de transporte de personal que cumplan con todas las certificaciones, permisos y licencias establecidas en la Ley de Transporte P\u00fablico del Estado de San Luis Potos\u00ed.<\/p>\n<p>Lo anterior porque debido al crecimiento de empresas as\u00ed como de trabajadores en la Zona Industrial, las empresas se han visto en la necesidad de licitar el servicio de transporte de personal, contratando el m\u00e1s econ\u00f3mico, sin tomar en cuenta las certificaciones, permisos de la Secretar\u00eda de Comunicaciones y Transportes, seguros de responsabilidad civil, seguro de pasajero, \u00a0y sin checar la licencia del operador si est\u00e1 calificado y certificado por la SCT.<\/p>\n<p>En el punto de acuerdo aprobado se se\u00f1ala que de acuerdo al estudio realizado por la Uni\u00f3n de Usuarios de la Zona Industrial (UUZI) \u00a0actualmente en la Zona Industrial hay 520 empresas, m\u00e1s de 400 mil trabajadores y registra un flujo vehicular diario de 160 mil autom\u00f3viles entre particulares y colectivos.<\/p>\n<p>Debido a dicho incremento las empresas de la Zona Industrial han tenido la necesidad de contratar servicio de transporte de personal, el cual licitan y toman el m\u00e1s econ\u00f3mico, sin tomar en cuenta las certificaciones, permisos de la \u00a0SCT, seguros de Responsabilidad Civil, seguro de pasajero, y sin checar\u00a0 la licencia del operador si est\u00e1 calificado y certificado por SCT.<\/p>\n<p>El 90 % de los operadores que laboran en la Zona Industrial, en alg\u00fan momento fueron operadores del transporte P\u00fablico los cuales traen los mismos paradigmas del pasado: Est\u00e9reos a todo volumen, exceso de velocidad, uso del celular en movimiento, aud\u00edfonos en movimiento; este sistema anacr\u00f3nico no es supervisado por la SCT, lo que ocasiona que no haya calidad de vialidad en la movilidad empresarial.<\/p>\n<p>Por tal motivo, es indispensable regular a las empresas de transporte de personal de la Zona Industrial, las cuales, en su mayor\u00eda son for\u00e1neas y no est\u00e1n registradas en San Luis Potos\u00ed \u00a0en la Secretar\u00eda de Comunicaciones y Transportes y no pagan sus impuestos en nuestra entidad.<\/p>\n<p>Por ello, hay que asegurarse que cumplan con todos los requisitos que marca la ley para garantizar un buen servicio; sostiene el punto de acuerdo aprobado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A propuesta del diputado Sergio Enrique Desfassiux Cabello, el Poder Legislativo aprob\u00f3 un punto de acuerdo para exhortar a los<\/p>\n","protected":false},"author":2,"featured_media":8867,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/8866"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=8866"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/8866\/revisions"}],"predecessor-version":[{"id":8868,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/8866\/revisions\/8868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/8867"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=8866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=8866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=8866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}