{"id":8897,"date":"2018-03-07T08:21:32","date_gmt":"2018-03-07T14:21:32","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=8897"},"modified":"2018-03-08T08:22:24","modified_gmt":"2018-03-08T14:22:24","slug":"aplicacion-de-la-ley-base-de-la-convivencia-social-jm-carreras","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/aplicacion-de-la-ley-base-de-la-convivencia-social-jm-carreras\/","title":{"rendered":"APLICACI\u00d3N DE LA LEY, BASE DE LA CONVIVENCIA SOCIAL: JM CARRERAS"},"content":{"rendered":"<ul>\n<li style=\"font-weight: 400;\"><b>Asiste Gobernador del Estado a la celebraci\u00f3n del D\u00eda del Juez Mexicano.<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u201cComo lo dijo Sim\u00f3n Bol\u00edvar, el libertador de Am\u00e9rica, la justicia es la reina de las virtudes republicanas y con ella se sostiene la igualdad y la libertad de las personas; para preservar estos valores es necesario que el sistema de procuraci\u00f3n y administraci\u00f3n de justicia gravite en torno a los principios de respeto a los Derechos Humanos, Perspectiva de G\u00e9nero y como eje toral, la reparaci\u00f3n del da\u00f1o\u201d dijo el Gobernador del Estado Juan Manuel Carreras en el marco de la celebraci\u00f3n del d\u00eda de las juezas y jueces mexicanos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El mandatario estatal, quien fue convocado como invitado de honor a esta reuni\u00f3n, expuso que \u201cla administraci\u00f3n de la justicia con oportunidad, transparencia y \u00e9tica constituye el \u00a0fundamento de nuestras instituciones\u201d. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">En su discurso Carreras L\u00f3pez cit\u00f3 al Presidente del Supremo Tribunal de Justicia de la Naci\u00f3n (STJN), Luis Mar\u00eda Aguilar Morales, al se\u00f1alar que un elemento fundamental de la convivencia social del Estado democr\u00e1tico de derecho, es la justicia, como el mejor ant\u00eddoto contra la violencia \u201csin duda la reflexi\u00f3n del ministro Aguilar no se limita s\u00f3lo al \u00e1mbito del poder judicial sino una concepci\u00f3n extensa, de hacer lo que M\u00e9xico espera de quienes nos dedicamos al quehacer p\u00fablico\u201d. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Agreg\u00f3 que la justicia debe ser en todos los \u00e1mbitos como el caso de la deuda de sociedad tenemos para la erradicaci\u00f3n de la violencia contra las mujeres y el fortalecimiento de la equidad de g\u00e9nero, por lo que se sum\u00f3 al reconocimiento a la magistrada Mar\u00eda Elena Palomino, por su perseverancia y labor a lo largo de 43 a\u00f1os en el poder judicial.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El jefe del ejecutivo estatal presenci\u00f3 la conferencia magistral dictada por la abogada Ana Katiria Su\u00e1rez, acompa\u00f1ado de la Presidenta de la Junta Directiva del DIF Estatal Lorena Valle Rodr\u00edguez as\u00ed como de funcionarios de su gabinete como el secretario General de Gobierno Alejandro Leal Tov\u00edas y el secretario de Seguridad P\u00fablica del Estados Ernesto Pineda Arteaga. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Asimismo, estuvieron presentes, el presidente del Supremo Tribunal de Justicia del Estado (STJE), Juan Paulo Almaz\u00e1n, el Fiscal General del Estado Federico Garza Herrera, el Rector de la UASLP Manuel Ferm\u00edn Villar Rubio; el Comandante de la XII Zona Militar Juan Francisco Salas \u00c1vila; la diputada Cecilia Gonz\u00e1lez Gordoa entre otros invitados y miembros del gremio de abogados de la entidad. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asiste Gobernador del Estado a la celebraci\u00f3n del D\u00eda del Juez Mexicano. \u201cComo lo dijo Sim\u00f3n Bol\u00edvar, el libertador de<\/p>\n","protected":false},"author":2,"featured_media":8898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/8897"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=8897"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/8897\/revisions"}],"predecessor-version":[{"id":8899,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/8897\/revisions\/8899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/8898"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=8897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=8897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=8897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}