{"id":8906,"date":"2018-03-07T08:26:52","date_gmt":"2018-03-07T14:26:52","guid":{"rendered":"http:\/\/www.radiodigitaltamazunchale.com\/landing\/?p=8906"},"modified":"2018-03-08T08:29:42","modified_gmt":"2018-03-08T14:29:42","slug":"se-impulsa-ley-estatal-para-la-produccion-y-comercializacion-del-mezcal-para-slp","status":"publish","type":"post","link":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/uncategorized\/se-impulsa-ley-estatal-para-la-produccion-y-comercializacion-del-mezcal-para-slp\/","title":{"rendered":"SE IMPULSA LEY ESTATAL PARA LA PRODUCCI\u00d3N Y COMERCIALIZACI\u00d3N DEL MEZCAL PARA SLP"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Debido a que el mezcal es un referente econ\u00f3mico, cultural y de desarrollo de nuestra entidad potosina y del pa\u00eds, el diputado Fernando Ch\u00e1vez M\u00e9ndez presentar\u00e1 una iniciativa para expedir la Ley del Mezcal para el Estado de San Luis Potos\u00ed fundamentada en la regulaci\u00f3n de su producci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dijo, \u201cesta ley es de gran importancia, debido a que San Luis Potos\u00ed es uno de los ocho estados del pa\u00eds que cuentan con la denominaci\u00f3n de origen que otorga el Instituto Mexicano de la Propiedad Industrial (IMPI), por ello, es importante dotar de un marco jur\u00eddico que regule la producci\u00f3n y comercializaci\u00f3n del mezcal\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cSe busca proteger a los peque\u00f1os productores que por a\u00f1os han estado en el olvido, se dotar\u00e1 de certeza a las familias que se dedican a su producci\u00f3n y que hoy en d\u00eda se han convertido en importantes fuentes de empleo\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con esta iniciativa de Ley del Mezcal, se busca regular su producci\u00f3n, potenciar la generaci\u00f3n de empleos para quienes mantienen sus ingresos de esta actividad, \u00a0as\u00ed como el establecimiento de pol\u00edticas p\u00fablicas con los recursos y medios ya existentes, direccionados a su fortalecimiento pleno, posicion\u00e1ndolo como un conexo cultural y tur\u00edstico del Estado y cumpliendo en todo momento con lo que dispone la Norma Oficial Mexicana respectiva.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta iniciativa tiene el objetivo, sin menoscabo por lo establecido en la Ley de Fomento al Desarrollo Rural Sustentable del Estado de San Luis Potos\u00ed, de lo siguiente: Proteger la cadena productiva del mezcal en todas sus etapas. Impulsar la comercializaci\u00f3n del mezcal. Identificar las zonas de producci\u00f3n del mezcal dentro de los municipios incluidos en la Denominaci\u00f3n de Origen Mezcal. Fomentar el apoyo de las organizaciones de mezcaleros, a efecto de alcanzar la protecci\u00f3n y el aprovechamiento en la producci\u00f3n y comercializaci\u00f3n del mezcal. \u00a0Coordinar a las dependencias estatales, en el apoyo de las organizaciones de productores y comercializadores del mezcal. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Promover entre las organizaciones de productores y comercializadores, en coordinaci\u00f3n con los \u00f3rdenes de gobierno, el cumplimiento de las Normas Oficiales Mexicanas y dem\u00e1s disposiciones legales aplicables a la autenticidad y calidad del mezcal. \u00a0\u00a0Incentivar las acciones pertinentes para mejorar la infraestructura y equipos en las unidades de producci\u00f3n de mezcal, el desarrollo de marcas y la capacitaci\u00f3n en proceso de producci\u00f3n y de organizaci\u00f3n empresarial. As\u00ed como fortalecer esquemas integrales de comercializaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En la exposici\u00f3n de motivos de la iniciativa, que se presentar\u00eda ante el pleno del Congreso del Estado durante su sesi\u00f3n ordinaria de este jueves 8 de marzo del a\u00f1o en curso, se se\u00f1ala que el mezcal se ha convertido en uno de los productos m\u00e1s representativos de M\u00e9xico a nivel internacional, ya que su car\u00e1cter artesanal y su variedad de presentaciones lo han convertido en una bebida altamente demandada en mercados nacionales y extranjeros. \u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En M\u00e9xico son ocho los estados productores de mezcal: Zacatecas, Durango, Guerrero, Michoac\u00e1n, San Luis Potos\u00ed, Guanajuato, Tamaulipas y Oaxaca, todos ellos cuentan con la denominaci\u00f3n de origen del producto. Para el Instituto Mexicano de la Propiedad Industrial (IMPI), m\u00e1xima autoridad administrativa en materia de propiedad industrial en M\u00e9xico, esta bebida se ha convertido en motor de desarrollo econ\u00f3mico, especialmente en zonas marginadas, ya que en su mayor\u00eda, son peque\u00f1os productores, que con el crecimiento de la industria est\u00e1n obteniendo beneficios directos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se agrega que entre los beneficios que se identifican de los productos con denominaciones de origen est\u00e1 el del sector econ\u00f3mico, ya que brindan mayores oportunidades al sector productivo en M\u00e9xico, al mismo tiempo que se protege al consumidor. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">De acuerdo con datos oficiales, en los \u00faltimos a\u00f1os las ventas nacionales de mezcal crecieron 110 por ciento, al pasar de 320 mil litros en 2010 a 650 mil el a\u00f1o pasado.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En tanto, las exportaciones aumentaron 137 por ciento al moverse de 414 mil litros a 980 mil en el mismo lapso referido. Los principales mercados de exportaci\u00f3n son Estados Unidos, Inglaterra, Alemania, Francia, Espa\u00f1a, Italia, Australia y Chile<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a que el mezcal es un referente econ\u00f3mico, cultural y de desarrollo de nuestra entidad potosina y del pa\u00eds,<\/p>\n","protected":false},"author":2,"featured_media":8907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/8906"}],"collection":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/comments?post=8906"}],"version-history":[{"count":1,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/8906\/revisions"}],"predecessor-version":[{"id":8908,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/posts\/8906\/revisions\/8908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media\/8907"}],"wp:attachment":[{"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/media?parent=8906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/categories?post=8906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiodigitaltamazunchale.com\/landing\/wp-json\/wp\/v2\/tags?post=8906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}